{"id":1063,"date":"2017-01-04T07:00:33","date_gmt":"2017-01-04T09:00:33","guid":{"rendered":"http:\/\/tgitoday.com.br\/?p=1063"},"modified":"2023-03-22T10:39:11","modified_gmt":"2023-03-22T13:39:11","slug":"ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/","title":{"rendered":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal"},"content":{"rendered":"\n<p>Parab\u00e9ns, brasileiros por terem enfrentado de cabe\u00e7a erguida os \u00faltimos anos mais desafiadores da hist\u00f3ria do nosso pa\u00eds! Supera\u00e7\u00e3o \u00e9 a palavra do ano!<\/p>\n\n\n\n<p>Quantos aprendizados e oportunidades para co-criarmos um novo pa\u00eds e uma nova hist\u00f3ria de supera\u00e7\u00e3o n\u00e3o apenas individual, de cada fam\u00edlia, de cada profissional, de cada empresa, mas tamb\u00e9m a reinven\u00e7\u00e3o de modelos de neg\u00f3cio<strong style=\"color: #ff6944;\">&nbsp;<\/strong>para a prosperidade econ\u00f4mica de todos.<\/p>\n\n\n\n<p>Uma nova era inicia-se privilegiando a criatividade, <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/como-encontrar-seu-proposito\/\">o prop\u00f3sito,<\/a> um olhar mais colaborativo e principalmente o resgate de valores essenciais como \u00e9tica, transpar\u00eancia e respeito aos direitos de cidad\u00e3o.<\/p>\n\n\n\n<p>Talvez, voc\u00ea ainda ache estranho eu comemorar e dar parab\u00e9ns, afinal ainda estamos no fundo do po\u00e7o, milhares de pessoas est\u00e3o desempregadas, cat\u00e1strofes est\u00e3o acontecendo e a prosperidade econ\u00f4mica simplesmente resolveu sumir!<\/p>\n\n\n\n<p>E, voc\u00ea tem raz\u00e3o, ainda temos alguns anos desafiadores e estes s\u00e3o fatos que vivemos, inclusive eu compartilho alguns dados aqui, para voc\u00ea ter visibilidade do que acontece e usar essas informa\u00e7\u00f5es para agir a partir de agora em busca de oportunidades para trabalhar a sua prosperidade econ\u00f4mica.<\/p>\n\n\n\n<p><strong>A crise afetou diretamente cada um de n\u00f3s e principalmente gerou um sentimento de inseguran\u00e7a constante, medo de perder o emprego, e falta de confian\u00e7a no pa\u00eds.<\/strong><\/p>\n\n\n\n<p>\u2192 Vivemos a pior crise econ\u00f4mica, pol\u00edtica, de \u00e9tica e de confian\u00e7a da hist\u00f3ria do Brasil. Para ser mais espec\u00edfica, em novembro de 2015, o nosso pa\u00eds atingiu o recorde hist\u00f3rico de baixa de confian\u00e7a pelos empres\u00e1rios e consumidores.<\/p>\n\n\n\n<p>\u2192 Segundo o IBGE,&nbsp;<a style=\"color: #82a892; text-decoration: underline;\" href=\"http:\/\/g1.globo.com\/economia\/noticia\/2016\/08\/desemprego-fica-em-116-no-trimestre-encerrado-em-julho.html\">a popula\u00e7\u00e3o desocupada no Brasil chegou a 11,8 milh\u00f5es de pessoas em julho<\/a>. No acumulado dos sete primeiros meses de 2016, o <a style=\"color: #82a892; text-decoration: underline;\" href=\"http:\/\/g1.globo.com\/economia\/noticia\/2016\/08\/brasil-fecha-94-mil-vagas-de-trabalho-formais-em-julho.html\">pa\u00eds perdeu 623 mil empregos formais<\/a>. Julho foi o 16\u00ba m\u00eas seguido de fechamento de vagas com carteira assinada.<\/p>\n\n\n\n<p><strong>Talvez por n\u00e3o conseguir sustentar sua pr\u00f3pria fam\u00edlia, o brasileiro tornou-se preocupado e infeliz. <\/strong><\/p>\n\n\n\n<p>\u2192 Detectou-se que os brasileiros nunca estiveram t\u00e3o insatisfeitos, revela pesquisa feita pelo Instituto Brasileiro de Opini\u00e3o e Estat\u00edstica (Ibope) para a Confedera\u00e7\u00e3o Nacional da Ind\u00fastria (CNI &#8211; mar\u00e7o 2015).<\/p>\n\n\n\n<p>\u2192 Em mar\u00e7o, o \u00cdndice de Satisfa\u00e7\u00e3o com a Vida caiu 2,8% na compara\u00e7\u00e3o com dezembro de 2015 e atingiu 92,4 pontos, o menor patamar desde o in\u00edcio da s\u00e9rie hist\u00f3rica iniciada em mar\u00e7o de 1999. Na compara\u00e7\u00e3o com mar\u00e7o de 2015, a queda foi de 2,4%.<\/p>\n\n\n\n<p><strong>Em todas as crises existem in\u00fameras oportunidades e quero trazer exatamente formas criativas de enxergar esses dados e como podem impactar positivamente a gente.<\/strong><\/p>\n\n\n\n<p>\u2192 Segundo Henrique Meirelles, ministro da fazenda \u201c a perspectiva \u00e9 de crescimento a partir do fim de 2016 e in\u00edcio de 2017\u201d.<\/p>\n\n\n\n<p>\u2192 2017 ser\u00e1 um ano crucial e um divisor de \u00e1guas para a sua satisfa\u00e7\u00e3o e prosperidade econ\u00f4mica! Acredito que j\u00e1 atingimos o fundo do po\u00e7o, agora, \u00e9 s\u00f3 \u201csegurar a corda o come\u00e7ar a subir\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que voc\u00ea pode fazer a partir de agora para acreditar que o ano ser\u00e1 o ano da sua prosperidade econ\u00f4mica?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Tenha coragem<\/h3>\n\n\n\n<p>Voc\u00ea e milhares de pessoas tem o desejo de mudar de vida, quer estar mais equilibrado, mas n\u00e3o sabe como ter coragem e nem <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\" target=\"_blank\" rel=\"noreferrer noopener\">o passo 1 para come\u00e7ar<\/a>. Entenda, que voc\u00ea \u00e9 o grande co-criador da sua hist\u00f3ria. N\u00e3o existe ningu\u00e9m, al\u00e9m de voc\u00ea 100% respons\u00e1vel pelo seu sucesso!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Construa uma rota<\/h3>\n\n\n\n<p>Existe sim, basta acreditar&#8230; Um futuro que come\u00e7a agora, com sonhos, expectativas. Cheio de oportunidades, por\u00e9m s\u00f3 se tornar\u00e1 realidade para aqueles que estiverem dispostos a lutar pelos seus projetos.<a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superar-crise-e-melhorar-sua-vida\/\" target=\"_blank\" rel=\"noreferrer noopener\"> Assuma a partir de agora as r\u00e9deas da sua vida<\/a> e dos seus caminhos. Se voc\u00ea n\u00e3o construir a sua rota, ningu\u00e9m far\u00e1 por voc\u00ea!<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Foque no que \u00e9 importante<\/h3>\n\n\n\n<p>Eu sei, n\u00e3o apenas voc\u00ea, mas o inconsciente coletivo do nosso pa\u00eds sente muito <a style=\"color: #82a892; text-decoration: underline;\" href=\"http:\/\/blog.tgitoday.com.br\/superar-o-medo-do-fracasso\/\">medo<\/a>, inseguran\u00e7a e tem muitas d\u00favidas relacionadas ao futuro. O que eu te pe\u00e7o \u00e9 para que voc\u00ea foque naquilo que voc\u00ea controla. Sonhe ser mais reconhecido no que voc\u00ea faz ou busque viver mais alinhado com o seu estilo de vida. Pare de querer ter raz\u00e3o ou se mostrar mais do que voc\u00ea \u00e9 para os outros.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Respeite-se mais<\/h3>\n\n\n\n<p>Momentos de ruptura, de viradas de ano s\u00e3o oportunidades para reflex\u00e3o e resgate de valores. Pergunte-se: quem eu sou? O que eu mais valorizo? O que eu n\u00e3o tolero mais? Quem eu quero perto de mim que est\u00e1 contribuindo para o meu crescimento pessoal e profissional. Fa\u00e7a um favor para voc\u00ea mesmo: respeite-se.<\/p>\n\n\n\n<p>Agrade\u00e7a, acredite e entre em a\u00e7\u00e3o no hoje e no agora.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Medita\u00e7\u00e3o Gratuita<\/h2>\n\n\n\n<p>Para enfrentar este momento de mudan\u00e7a do mundo, o primeiro passo \u00e9 estar e viver no momento presente, com foco nos seus objetivos. <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/pratica-mindfulness-gratuita\" target=\"_blank\" rel=\"noreferrer noopener\">Baixe gratuitamente<\/a> a <strong>Medita\u00e7\u00e3o Mindfulness de Aten\u00e7\u00e3o Plena<\/strong> e treine seu foco hoje!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Parab\u00e9ns, brasileiros por terem enfrentado de cabe\u00e7a erguida os \u00faltimos anos mais desafiadores da hist\u00f3ria do nosso pa\u00eds! Supera\u00e7\u00e3o \u00e9 a palavra do ano! Quantos aprendizados e oportunidades para co-criarmos um novo pa\u00eds e uma nova hist\u00f3ria de supera\u00e7\u00e3o n\u00e3o apenas individual, de cada fam\u00edlia, de cada profissional, de cada empresa, mas tamb\u00e9m a reinven\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":1064,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1063","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-04T09:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T13:39:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/01\/2017_ano-prospero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal\",\"datePublished\":\"2017-01-04T09:00:33+00:00\",\"dateModified\":\"2023-03-22T13:39:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\"},\"wordCount\":856,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\",\"name\":\"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2017-01-04T09:00:33+00:00\",\"dateModified\":\"2023-03-22T13:39:11+00:00\",\"description\":\"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa","description":"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/","og_locale":"pt_BR","og_type":"article","og_title":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa","og_description":"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.","og_url":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/","og_site_name":"Blog Ligia Costa","article_published_time":"2017-01-04T09:00:33+00:00","article_modified_time":"2023-03-22T13:39:11+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/01\/2017_ano-prospero.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/"},"author":{"name":"","@id":""},"headline":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal","datePublished":"2017-01-04T09:00:33+00:00","dateModified":"2023-03-22T13:39:11+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/"},"wordCount":856,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/","url":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/","name":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2017-01-04T09:00:33+00:00","dateModified":"2023-03-22T13:39:11+00:00","description":"O pa\u00eds enfrentou uma crise que gerou muito desemprego e satisfa\u00e7\u00e3o. Agora \u00e9 hora de dedicar-se para que 2017 seja o ano da sua prosperidade econ\u00f4mica.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/ano-crucial-para-sua-prosperidade-economica-e-satisfacao-pessoal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Este \u00e9 o ano crucial para a sua prosperidade econ\u00f4mica e satisfa\u00e7\u00e3o pessoal"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1063","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1063"}],"version-history":[{"count":5,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1063\/revisions"}],"predecessor-version":[{"id":4847,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1063\/revisions\/4847"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/1064"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1063"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1063"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1063"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}