{"id":1125,"date":"2016-01-07T08:00:11","date_gmt":"2016-01-07T10:00:11","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=240"},"modified":"2023-03-22T14:05:28","modified_gmt":"2023-03-22T17:05:28","slug":"mediacao-de-conflitos","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/","title":{"rendered":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados"},"content":{"rendered":"\n<p>Recentemente participei de um caf\u00e9 da manh\u00e3 em um instituto super reconhecido em S\u00e3o Paulo, onde o tema abordado foi media\u00e7\u00e3o de conflitos.&nbsp;O que me levou a participar deste evento foi a minha curiosidade sobre como as empresas e as pessoas em geral, est\u00e3o lidando com este tema que, infelizmente, virou t\u00e3o frequente e comum.<\/p>\n\n\n\n<p>O conflito sempre existiu. \u00c9 inerente do ser humano viver em conflito, afinal, a partir do momento que pessoas n\u00e3o concordam com as mesmas regras ou tem pontos de vista distintos sobre o mesmo assunto, j\u00e1 podemos dizer que um conflito se instalou. Por isso \u00e9 sempre importante que a media\u00e7\u00e3o de conflitos tamb\u00e9m esteja presente, para evitar desentendimentos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Media\u00e7\u00e3o de conflitos na vida pessoal e profissional<\/h2>\n\n\n\n<p>Os conflitos podem ser expl\u00edcitos ou velados e a grande maioria de n\u00f3s simplesmente finge que nada est\u00e1 existindo, at\u00e9 que a rela\u00e7\u00e3o fica insustent\u00e1vel.&nbsp;N\u00e3o importa se estamos falando de profissionais ou da nossa vida pessoal.<\/p>\n\n\n\n<p>Um dado curioso: quanto maior o n\u00edvel hier\u00e1rquico, maior o jogo de poder e a necessidade de fazer a sua verdade prevalecer, consequentemente, o ego sobressai ao bom senso. U\u00e9! N\u00e3o era de se esperar de um l\u00edder ou de um pai de fam\u00edlia uma media\u00e7\u00e3o de conflitos nata? A busca do senso comum? Onde nos perdemos? E, como lidar com isso?<\/p>\n\n\n\n<p>Me surpreendi ao saber que as empresas e fam\u00edlias est\u00e3o buscando absurdamente a contrata\u00e7\u00e3o de servi\u00e7os de experts em media\u00e7\u00e3o de conflitos para solucionarem seus problemas. A situa\u00e7\u00e3o chegou a um ponto onde j\u00e1 n\u00e3o se existe conversa entre as partes. Isto \u00e9 grave, ao menos para mim. \u00c9 muito grave. Socorro! Acordem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Thank God it&#8217;s Today &#8211;&nbsp;O que a escola n\u00e3o nos ensinou:<\/h2>\n\n\n\n<p><strong>#1 Dica &#8211; <\/strong>Precisamos praticar em nossa sociedade o \u201csaber ouvir sem julgar\u201d, pratique uma <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/gestao-humanizada\/\" target=\"_blank\" rel=\"noreferrer noopener\">gest\u00e3o mais humanizada<\/a>. Simplesmente ouvir e entender o ponto de vista de todos os envolvidos na situa\u00e7\u00e3o \u00e9 a sa\u00edda para alguns conflitos<strong>.<\/strong><\/p>\n\n\n\n<p><strong>#2 Dica &#8211; <\/strong>Todos podemos praticar a media\u00e7\u00e3o de conflitos em nossas vidas. Ningu\u00e9m tem a verdade absoluta. Converse abertamente sobre o problema e se responsabilize pela sua parte.<\/p>\n\n\n\n<p><strong>#3 Dica &#8211; <\/strong>Seja mais flex\u00edvel e aprenda a cada dia com o outro, d\u00ea <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/feedback\/\">feedback<\/a> com frequ\u00eancia. N\u00e3o espere a bomba estourar.<\/p>\n\n\n\n<p><strong>#4 Dica &#8211; <\/strong>Aprenda a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/aprenda-dizer-nao\/\">dizer n\u00e3o<\/a> e respeitar seus valores!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Webin\u00e1rio Gratuito<\/h2>\n\n\n\n<p>Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e Descubra os 4 passos para voc\u00ea equilibrar a sua vida pessoal e profissional, criar metas e focar no que \u00e9 importante. S\u00f3 assim voc\u00ea ter\u00e1 alta performance.<\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES \ud83d\ude42<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente participei de um caf\u00e9 da manh\u00e3 em um instituto super reconhecido em S\u00e3o Paulo, onde o tema abordado foi media\u00e7\u00e3o de conflitos.&nbsp;O que me levou a participar deste evento foi a minha curiosidade sobre como as empresas e as pessoas em geral, est\u00e3o lidando com este tema que, infelizmente, virou t\u00e3o frequente e comum. [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-1125","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lideranca-humanizada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados<\/title>\n<meta name=\"description\" content=\"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados\" \/>\n<meta property=\"og:description\" content=\"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-07T10:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T17:05:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/Mediacao-de-conflitos-e-preciso-ouvir-e-entender-todos-os-lados.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados\",\"datePublished\":\"2016-01-07T10:00:11+00:00\",\"dateModified\":\"2023-03-22T17:05:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Lideran\u00e7a humanizada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\",\"name\":\"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-01-07T10:00:11+00:00\",\"dateModified\":\"2023-03-22T17:05:28+00:00\",\"description\":\"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados","description":"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/","og_locale":"pt_BR","og_type":"article","og_title":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados","og_description":"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.","og_url":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-01-07T10:00:11+00:00","article_modified_time":"2023-03-22T17:05:28+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/Mediacao-de-conflitos-e-preciso-ouvir-e-entender-todos-os-lados.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/"},"author":{"name":"","@id":""},"headline":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados","datePublished":"2016-01-07T10:00:11+00:00","dateModified":"2023-03-22T17:05:28+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Lideran\u00e7a humanizada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/","url":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/","name":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-01-07T10:00:11+00:00","dateModified":"2023-03-22T17:05:28+00:00","description":"Empresas e fam\u00edlias buscam media\u00e7\u00e3o de conflitos. Entender o ponto de vista das pessoas e ser flex\u00edvel s\u00e3o atitudes que podem evitar desentendimentos.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/mediacao-de-conflitos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Media\u00e7\u00e3o de conflitos: \u00e9 preciso ouvir e entender todos os lados"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1125"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions"}],"predecessor-version":[{"id":5176,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1125\/revisions\/5176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4246"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1125"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1125"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}