{"id":1129,"date":"2016-01-25T08:00:46","date_gmt":"2016-01-25T10:00:46","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=251"},"modified":"2023-03-22T13:54:48","modified_gmt":"2023-03-22T16:54:48","slug":"medico-ou-marketeiro-o-que-voce-faz","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/","title":{"rendered":"M\u00e9dico ou marketeiro: n\u00e3o importa quem voc\u00ea \u00e9, mas o que faz?"},"content":{"rendered":"\n<p>Recentemente viajei para Santa Clara, Calif\u00f3rnia, para estudar sobre marketing digital. Existiam aproximadamente 700 pessoas e 10 Brasileiros. Curiosamente, no grupo dos brasileiros estava um M\u00e9dico Otorrinolaringologista e Cirurgi\u00e3o Pl\u00e1stico de Face que atua em Campo Grande, Mato Grosso do Sul, ambos eram ou m\u00e9dico ou marketeiro.<\/p>\n\n\n\n<p>Devo confessar que achei um pouco estranho um m\u00e9dico estar participando de um congresso de Marketing. Minha curiosidade foi tamanha que durante nosso primeiro bate papo j\u00e1 o questionei sobre a expectativa dele com rela\u00e7\u00e3o ao assunto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ex-futura m\u00e9dica<\/h2>\n\n\n\n<p>Naquele momento, Dr. Marco Aur\u00e9lio Asato, com sua sabedoria oriental me respondeu: quero transformar a medicina no Brasil. Os m\u00e9dicos precisam aprimorar o trabalho de relacionamento com seus pacientes e passar a usar a tecnologia a nosso favor.<\/p>\n\n\n\n<p>Uau, algu\u00e9m que fala a minha l\u00edngua. Como me identifiquei, contei a ele que aos 16 anos, eu, Ligia Costa, havia prestado vestibular para Medicina.<\/p>\n\n\n\n<p>N\u00e3o fui bem sucedida na primeira tentativa e, mesmo fazendo cursinho de Biol\u00f3gicas, a incerteza desta fase pr\u00e9-adulta fez com que eu passasse de m\u00e9dica a marketeira em apenas 6 meses.&nbsp;E assim iniciou-se <a style=\"color: #82a892; text-decoration: underline;\" href=\"http:\/\/ligiacosta.com.br\/pages\/sobre-ligia-costa\/\">minha carreira<\/a> no mundo de Marketing, Comunica\u00e7\u00e3o e Tecnologia.&nbsp;Descobri ao longo destes 20 anos que existe muita sinergia nestas duas profiss\u00f5es.<\/p>\n\n\n\n<p>M\u00e9dico ou marketeiro, voc\u00ea precisa aprender a lidar com as pessoas, seja em projetos ou em suas necessidades de sa\u00fade. E muito est\u00e1 em jogo no seu trabalho: a sa\u00fade e o bem estar de algu\u00e9m ou a imagem e reputa\u00e7\u00e3o de uma empresa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">M\u00e9dico ou marketeiro: 3 semelhan\u00e7as que comprovam que n\u00e3o importa quem voc\u00ea \u00e9, mas, sim, o que voc\u00ea faz<\/h2>\n\n\n\n<p><strong>#1) M\u00e9dico ou marketeiro &nbsp;s\u00f3 s\u00e3o reconhecidos e bem avaliados em suas profiss\u00f5es, quando compreendem em profundidade as necessidades do seu cliente\/paciente e criam estrat\u00e9gias que solucionam\/ previnem\/ antecipam os seus problemas.<\/strong><\/p>\n\n\n\n<p><strong>#2) M\u00e9dico ou marketeiro passam a maior parte do seu dia atendendo pessoas, ouvindo seus dilemas, expectativas e frustra\u00e7\u00f5es. A agenda de ambos \u00e9 completamente lotada de reuni\u00f5es, seja com clientes, fornecedores ou parceiros, sem falar das viagens e congressos.<\/strong><\/p>\n\n\n\n<p><strong>#3) M\u00e9dico ou marketeiro tem como miss\u00e3o <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/trabalhar-e-ser-feliz\/\" target=\"_blank\" rel=\"noreferrer noopener\">ajudar pessoas a serem mais felizes<\/a><\/strong>.<strong> Ambos s\u00e3o empreendedores que tem como prop\u00f3sito ajudar pessoas, transformar e buscar solu\u00e7\u00f5es inovadoras com o apoio da tecnologia como ferramenta de suporte.<\/strong><\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">Leia mais<\/h3>\n\n\n\n<p><strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/trabalhar-e-ser-feliz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ei, acredite: \u00e9 poss\u00edvel trabalhar, pagar as contas e ser feliz<\/a><\/strong><\/p>\n<p>\n\n\n\n<\/p>\n<p><strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/voce-esta-alinhado-ao-seu-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">Voc\u00ea est\u00e1 alinhado ao seu prop\u00f3sito? Descubra em 5 perguntas<\/a><\/strong><\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Portanto, hoje, compreendo que, muito al\u00e9m do r\u00f3tulo de uma profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano querendo transformar, influenciar e deixar um legado positivo.<\/p>\n\n\n\n<p>Foi muito bacana ver um m\u00e9dico querendo trazer princ\u00edpios de Marketing para transformar a Medicina e a marketeira querendo ajudar as pessoas atrav\u00e9s da neuroci\u00eancia.<\/p>\n\n\n\n<p>Estamos todos conectados atrav\u00e9s da tecnologia, que \u00e9 a ferramenta que nos permite sermos todos comunicadores.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Webin\u00e1rio Gratuito<\/h2>\n\n\n\n<p>Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e Descubra os 4 passos para voc\u00ea equilibrar a sua vida pessoal e profissional, criar metas e focar no que \u00e9 importante. S\u00f3 assim voc\u00ea ter\u00e1 alta performance.<\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Recentemente viajei para Santa Clara, Calif\u00f3rnia, para estudar sobre marketing digital. Existiam aproximadamente 700 pessoas e 10 Brasileiros. Curiosamente, no grupo dos brasileiros estava um M\u00e9dico Otorrinolaringologista e Cirurgi\u00e3o Pl\u00e1stico de Face que atua em Campo Grande, Mato Grosso do Sul, ambos eram ou m\u00e9dico ou marketeiro. Devo confessar que achei um pouco estranho um [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4235,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1129","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz<\/title>\n<meta name=\"description\" content=\"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz\" \/>\n<meta property=\"og:description\" content=\"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-25T10:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T16:54:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/Medico-ou-marketeiro-nao-importa-quem-voce-e-mas-o-que-faz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"M\u00e9dico ou marketeiro: n\u00e3o importa quem voc\u00ea \u00e9, mas o que faz?\",\"datePublished\":\"2016-01-25T10:00:46+00:00\",\"dateModified\":\"2023-03-22T16:54:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\"},\"wordCount\":589,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\",\"name\":\"M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-01-25T10:00:46+00:00\",\"dateModified\":\"2023-03-22T16:54:48+00:00\",\"description\":\"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e9dico ou marketeiro: n\u00e3o importa quem voc\u00ea \u00e9, mas o que faz?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz","description":"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/","og_locale":"pt_BR","og_type":"article","og_title":"M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz","og_description":"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.","og_url":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-01-25T10:00:46+00:00","article_modified_time":"2023-03-22T16:54:48+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/Medico-ou-marketeiro-nao-importa-quem-voce-e-mas-o-que-faz.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/"},"author":{"name":"","@id":""},"headline":"M\u00e9dico ou marketeiro: n\u00e3o importa quem voc\u00ea \u00e9, mas o que faz?","datePublished":"2016-01-25T10:00:46+00:00","dateModified":"2023-03-22T16:54:48+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/"},"wordCount":589,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/","url":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/","name":"M\u00e9dico ou Marketeiro: n\u00e3o importa quem voc\u00ea \u00e9 e sim o que voc\u00ea faz","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-01-25T10:00:46+00:00","dateModified":"2023-03-22T16:54:48+00:00","description":"M\u00e9dico ou marketeiro \u00e9 apenas um r\u00f3tulo da profiss\u00e3o, existe a inten\u00e7\u00e3o de um ser humano transformar, influenciar e deixar um legado para o mundo.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"M\u00e9dico ou marketeiro: n\u00e3o importa quem voc\u00ea \u00e9, mas o que faz?"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1129"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1129\/revisions"}],"predecessor-version":[{"id":5138,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1129\/revisions\/5138"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4235"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}