{"id":1133,"date":"2016-02-15T08:00:19","date_gmt":"2016-02-15T10:00:19","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=267"},"modified":"2023-03-22T13:47:36","modified_gmt":"2023-03-22T16:47:36","slug":"primeiro-passo-em-direcao-aos-seus-sonhos","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/","title":{"rendered":"O dia perfeito \u00e9 hoje: primeiro passo em dire\u00e7\u00e3o aos seus sonhos"},"content":{"rendered":"\n<p>\u201cMe dou o direto de recusar servi\u00e7o a qualquer pessoa\u201d.&nbsp;No dia em que li esta frase, no fim de 2013, aos 36 anos, minha vida mudou completamente. O primeiro passo em dire\u00e7\u00e3o aos em dire\u00e7\u00e3o aos meus sonhos.<\/p>\n\n\n\n<p>Quatro meses antes, no dia 1 de setembro, eu viajava para Nova York. Cinco dias depois iria para Londres participar de um encontro com l\u00edderes regionais de Marketing e logo voltaria para o Brasil.<\/p>\n\n\n\n<p>Em apenas sete dias, havia cruzado Am\u00e9rica do Norte, Europa e Am\u00e9rica do Sul.&nbsp;Era apenas mais uma viagem de rotina. Afinal, cruzar oceanos em um curto espa\u00e7o de tempo era bastante comum em minha vida desde 2009.&nbsp;Por\u00e9m, o retorno desta viagem foi diferente.<\/p>\n\n\n\n<p>Dois dias ap\u00f3s desembarcar, no fat\u00eddico 11 de setembro, fui convocada para uma reuni\u00e3o. Na sala, estavam o vice-presidente de Marketing, o vice-presidente de Recursos Humanos e o Jur\u00eddico. Fui demitida.<\/p>\n\n\n\n<p>Sentimentos contradit\u00f3rios passaram pela minha cabe\u00e7a naquele momento. Ao mesmo tempo que me senti honrada por n\u00e3o fazerem a dispensa pelo telefone (o que \u00e9 muito comum em empresas globais), percebi que estava arrasada, pois meu dia havia chegado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Al\u00edvio e vergonha<\/h2>\n\n\n\n<p>Estava aliviada por sair de um lugar que j\u00e1 n\u00e3o me fazia mais feliz, mas muito triste e envergonhada, pois nunca tinha enfrentado uma demiss\u00e3o A realidade era que, a partir daquela data, pela primeira vez na minha vida, ap\u00f3s 18 anos de uma carreira s\u00f3lida como executiva de marketing, eu estava desempregada.<\/p>\n\n\n\n<p>N\u00e3o teria mais rotina nem para onde ir quando acordasse no dia seguinte. Tentei abandonar praticamente todos os h\u00e1bitos que me lembrassem aquela fase. Assumi integralmente o meu trabalho de <a style=\"color: #82a892; text-decoration: underline;\" href=\"http:\/\/blog.tgitoday.com.br\/multipotencialidade\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">m\u00e3e<\/a>, afinal, era hora de estar mais presente do que nunca com minha fam\u00edlia e filhas.<\/p>\n\n\n\n<p>Por\u00e9m, existia apenas uma rotina que n\u00e3o pude abandonar de imediato: as idas \u00e0 fisioterapia, em fun\u00e7\u00e3o de uma h\u00e9rnia cervical adquirida nos \u00faltimos anos, e ao cardiologista, que me ajudava no controle da redu\u00e7\u00e3o do colesterol que nunca esteve t\u00e3o alto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Sem um novo emprego<\/h2>\n\n\n\n<p>\u201cLigia, voc\u00ea est\u00e1 proibida de aceitar qualquer proposta de emprego nos pr\u00f3ximos tr\u00eas meses. Voc\u00ea precisa <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/4-passos-para-viver-com-mais-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">entender o que voc\u00ea quer.<\/a> Voc\u00ea merece um tempo.\u201d Ouvi esta frase do Beto, meu marido, na semana seguinte ap\u00f3s minha demiss\u00e3o.<\/p>\n\n\n\n<p>Na manh\u00e3 daquele dia recebi a liga\u00e7\u00e3o de um headhunter que me ofereceu um sal\u00e1rio monstruoso para ser diretora de uma empresa com duzentas pessoas abaixo de mim. Aquela oferta confortou o meu ego, mas ao mesmo tempo fui tomada por um p\u00e2nico s\u00f3 em imaginar que estaria sendo aprisionada novamente.<\/p>\n\n\n\n<p>Aqueles dizeres (\u201cvoc\u00ea merece um tempo\u201d) me encorajaram a recusar a proposta. Me permiti, nos meses que se seguiram, dedica\u00e7\u00e3o integral \u00e0 mim, \u00e0 minha fam\u00edlia e aos amigos. Deveria ter passado pela minha cabe\u00e7a &#8220;voc\u00ea est\u00e1 a caminho de dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos, Ligia&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">F\u00e9rias inspiradoras<\/h2>\n\n\n\n<p>Em dezembro de 2013, quase tr\u00eas meses ap\u00f3s a demiss\u00e3o, tirei as primeiras f\u00e9rias da minha vida em que eu estava literalmente de f\u00e9rias. Eu estava muito feliz, contemplativa, me sentindo plena por estar com o meu marido e com minhas duas filhas na Calif\u00f3rnia por quase 30 dias.<\/p>\n\n\n\n<p>Era um privil\u00e9gio. Viaj\u00e1vamos sem compromisso, sem press\u00e3o, sem ter que ler emails, sem ter que atender a reuni\u00f5es \u201cimportantes\u201d. Eu estava apenas de f\u00e9rias. S\u00f3 ali, curtindo cada dia, cada lugar, cada p\u00f4r do sol.<\/p>\n\n\n\n<p>No percurso de S\u00e3o Francisco \u00e0 Monterey, pela Highway One, paramos em um mirante para observar a migra\u00e7\u00e3o das baleias. Ap\u00f3s alguns minutos, atravessamos a estrada para tomar um caf\u00e9 em um pequeno bar.<\/p>\n\n\n\n<p>Ocupamos uma mesa bem pequenininha em frente ao balc\u00e3o cheio de doces maravilhosos onde pedimos caf\u00e9s e muffins de blueberry. De repente, passei a observar a atenciosa senhora que estava no caixa, administrando cautelosamente as finan\u00e7as do estabelecimento.<\/p>\n\n\n\n<p>Acima de sua cabe\u00e7a havia uma placa com os seguintes dizeres: \u201cWe reserve the right to refuse service to anyone\u201d. (\u201cNos reservamos ao direito de recusar servi\u00e7o a qualquer um\u201d, em tradu\u00e7\u00e3o livre). A frase naquela mini placa suja e antiga, se transformou no mantra que mudou minha vida.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Mensagem que liberta<\/h2>\n\n\n\n<p>Nunca uma frase fez tanto sentido como aquela naquele momento. Para mim foi libertador ver que os donos de um mini bar de estrada se posicionavam daquela forma perante os seus clientes e eu nunca havia me permitido, ou melhor, nunca soube que teria o direito de recusar um servi\u00e7o a algu\u00e9m.<\/p>\n\n\n\n<p>A cultura brasileira e latina \u00e9 subserviente. Somos incentivados a dizer \u201csim\u201d sempre para tudo e todos. Damos sempre um jeitinho e nos condicionamos a agradar aos outros e n\u00e3o a n\u00f3s mesmos.<\/p>\n\n\n\n<p>Muito discretamente fotografei a placa. A partir daquele dia, n\u00e3o consegui mais pensar em outra coisa a n\u00e3o ser que \u201caquilo\u201d seria o meu novo lema. Dali em diante, reassumiria meu poder pessoal e n\u00e3o faria mais nada que n\u00e3o estivesse alinhado com meus valores pessoais e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superacao-de-gisele-bundchen-e-rafaela-silva\/\" target=\"_blank\" rel=\"noreferrer noopener\">objetivos de vida.<\/a> &#8220;O primeiro passo em dire\u00e7\u00e3o aos seus sonhos, Ligia&#8221;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Novo passo profissional<\/h2>\n\n\n\n<p><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/medico-ou-marketeiro-o-que-voce-faz\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u201cEu sou o que fa\u00e7o, eu fa\u00e7o o que sou\u201d.<\/a> Compreendi que eu e o meu novo passo profissional ser\u00edamos apenas uma \u00fanica pessoa.<\/p>\n\n\n\n<p>Compreendi que n\u00e3o abriria m\u00e3o de educar minhas filhas, nem de estar perto da minha fam\u00edlia por emprego convencional nenhum.<\/p>\n\n\n\n<p>Compreendi que minha paix\u00e3o e habilidade est\u00e3o em inspirar, liderar, provocar e impactar positivamente as pessoas.<\/p>\n\n\n\n<p>Compreendi que meu trabalho precisava ter significado. Eu n\u00e3o queria acordar para apenas cumprir protocolos e sim para transformar.<\/p>\n\n\n\n<p>Compreendi que todo o meu conhecimento e forma\u00e7\u00e3o s\u00e3o apenas ferramentas e t\u00e9cnicas, que me fortalecem e geram seguran\u00e7a para que eu possa exercer minha miss\u00e3o com excel\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Transi\u00e7\u00e3o de carreira<\/h2>\n\n\n\n<p>\u201cEstamos passando da era da tecnologia para a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/gestao-humanizada\" target=\"_blank\" rel=\"noreferrer noopener\">era da humaniza\u00e7\u00e3o<\/a>. A grande dificuldade da humanidade no momento \u00e9 a falta de foco. O mundo est\u00e1 globalizado, temos acesso a tudo a qualquer hora, por\u00e9m, enquanto n\u00e3o entendermos o que estamos buscando, continuaremos perdidos\u201d.<\/p>\n\n\n\n<p>Este foi o principal insight que tive, em setembro de 2014 \u2014 portanto, um ano depois de ser demitida \u2014, quando assumi efetivamente meu novo papel. Passei de executiva a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/fgts-no-microempreendimento\/\" target=\"_blank\" rel=\"noreferrer noopener\">empreendedora<\/a> e fundei o Thank God it\u2019s Today.<\/p>\n\n\n\n<p>Acredito que todo dia \u00e9 dia de aprender tudo que a escola n\u00e3o nos ensinou para termos <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/trabalhar-e-ser-feliz\/\" target=\"_blank\" rel=\"noreferrer noopener\">uma carreira e vida de sucesso.<\/a><strong>&nbsp;<\/strong>Notei que as pessoas est\u00e3o sempre esperando o momento ideal, o dia perfeito, sonham em ganhar na loteria, esperam o pr\u00f3ximo b\u00f4nus, a casa dos sonhos, o pr\u00edncipe encantado, a mulher perfeita.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O dia perfeito \u00e9 hoje<\/h2>\n\n\n\n<p>A grande maioria delega seu poder pessoal aos chefes, parceiros, postergam casamentos, maternidade, ficam esperando o superior definir seu pr\u00f3ximo passo profissional.&nbsp;Viver na espera \u00e9 comum e muito mais f\u00e1cil. Quantos desenham metas inalcan\u00e7\u00e1veis? Ou melhor (pior), nem metas tem?<\/p>\n\n\n\n<p>O avan\u00e7o tecnol\u00f3gico, por sua vez, chegou para mudar o comportamento e h\u00e1bitos da <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/geracao-selfie\" target=\"_blank\" rel=\"noreferrer noopener\">nossa gera\u00e7\u00e3o.<\/a> A mesma gera\u00e7\u00e3o que se perdeu completamente em fun\u00e7\u00e3o de tantas op\u00e7\u00f5es e precisa redescobrir-se urgentemente.<\/p>\n\n\n\n<p>Thank God It\u2019s Today surgiu porque acredito que o dia perfeito \u00e9 hoje! A melhor hora \u00e9 agora! O lugar \u00e9 este e n\u00e3o podemos esperar! Hoje \u00e9 e sempre ser\u00e1 o grande dia para dar o primeiro passo em dire\u00e7\u00e3o aos seus&nbsp;sonhos.<\/p>\n\n\n\n<p>O TGI Today surgiu para encorajar, inspirar a todos e relembrar que hoje \u00e9 o grande dia para voc\u00ea resgatar o seu poder pessoal, compreender a si pr\u00f3prio, reavaliar valores importantes para <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/recomecar-mudar-empreender-ou-crescer-qual-sua-escolha\/\" target=\"_blank\" rel=\"noreferrer noopener\">seu momento de vida.<\/a><\/p>\n\n\n\n<p>O mundo mudou, n\u00e3o temos mais tempo para viver infelizes ou doentes. Somos, sim, 100% respons\u00e1veis por nossa hist\u00f3ria. Chega de conformismo, de protagonizar o papel de v\u00edtima. Voc\u00ea precisa dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos.<\/p>\n\n\n\n<p>\u00c9 hora de liderar a sua pr\u00f3pria hist\u00f3ria, sua carreira, a sua vida! Hoje, sou empres\u00e1ria, fundadora do Thank God it\u2019s Today. Acredito que \u00e9 atrav\u00e9s do indiv\u00edduo que transformaremos o coletivo. Por isso, trabalho com pessoas e empresas, as incentivo a dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos atrav\u00e9s do TGI Today.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Estrat\u00e9gia pessoal, marketing e business<\/h2>\n\n\n\n<p>Em 2015, criei a TGI Today Business Academy que \u00e9 uma Escola de Estrat\u00e9gia Pessoal, Marketing e Business para pessoas inovadoras que sonham em viver e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/hoje-e-o-dia-ideal-para-voce-comecar-viver-com-mais-significado\/\" target=\"_blank\" rel=\"noreferrer noopener\">trabalhar com mais significado<\/a>, al\u00e9m de, logicamente, gerar lucro.<\/p>\n\n\n\n<p>A proposta do <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/business-academy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Business Academy<\/a> \u00e9 ampliar a consci\u00eancia de cada indiv\u00edduo, que compreender\u00e1 o novo momento do mundo, seus valores, habilidades individuais e se responsabilizar\u00e1 em contribuir, seja em sua profiss\u00e3o ou em um novo projeto de forma mais efetiva, \u00fanica, aut\u00eantica, imprimindo a sua marca pessoal.<\/p>\n\n\n\n<p>O Business Academy \u00e9 arrojado. N\u00e3o \u00e9 um programa convencional, n\u00e3o segue modelos acad\u00eamicos tradicionais (at\u00e9 porque n\u00e3o sou pedagoga, nem tenho habilita\u00e7\u00e3o formal de ensino).<\/p>\n\n\n\n<p>TGI Today tem como filosofia a experi\u00eancia, o storytelling, as viv\u00eancias, os fatos e cases de sucesso suportados com muitos anos de estudos e com inovadoras t\u00e9cnicas de marketing digital, business, design thinking, empreendedorismo criativo, modelos de neg\u00f3cios, gest\u00e3o financeira, neurolingu\u00edstica, intelig\u00eancia emocional, <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/meditacao-equilibrio-e-clareza\/\" target=\"_blank\" rel=\"noreferrer noopener\">espiritualidade<\/a>, t\u00e9cnicas de coaching, entre outras.<\/p>\n\n\n\n<p>Para que ele existisse, foi preciso que eu parasse e pensasse &#8220;Ligia, voc\u00ea precisa dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos&#8221;.<\/p>\n\n\n\n<p>TGI Today \u00e9 um programa voltado para pessoas e empresas que buscam fazer a diferen\u00e7a no mundo e dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. Para aqueles que compreendem um capitalismo mais consciente, que priorizam a busca pelo real prop\u00f3sito visando a lucratividade como consequ\u00eancia natural e verdadeira do seu business. Para todo que acreditam que hoje \u00e9 o grande dia de transformar seu plano B em plano A. Sempre encarei o Business Academy, para estas pessoas, como o primeiro passo em dire\u00e7\u00e3o ao seus sonhos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Business = life style, o primeiro passo em dire\u00e7\u00e3o aos seus sonhos<\/h2>\n\n\n\n<p>Minha filosofia de vida se tornou meu neg\u00f3cio. Minhas habilidades s\u00e3o minhas for\u00e7as e hoje vivo com muito mais significado. Consegui unir minhas paix\u00f5es que s\u00e3o ser m\u00e3e, construir uma fam\u00edlia harmoniosa e inspirar pessoas. Assim como eu, voc\u00ea pode, sim, dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos.<\/p>\n\n\n\n<p>\u00c9 tudo muito novo, muito especial e desafiador. Hoje compreendo que minha miss\u00e3o exige muita responsabilidade, trabalho e estudo.<\/p>\n\n\n\n<p>Estou pronta para viver plenamente este novo momento, trabalhar para inspirar e contribuir com a mudan\u00e7a.<\/p>\n\n\n\n<p>Thank God it\u2019s Today \u00e9 um estilo de vida, uma nova forma de pensar. \u00c9 acreditar, viver e vestir os seus valores diariamente. \u00c9 ser voc\u00ea e entender que o mundo precisa do seu melhor!<\/p>\n\n\n\n<p>Vem junto!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Webin\u00e1rio Gratuito<\/h2>\n\n\n\n<p>Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e Descubra os 4 passos para voc\u00ea equilibrar a sua vida pessoal e profissional, criar metas e focar no que \u00e9 importante. S\u00f3 assim voc\u00ea ter\u00e1 alta performance.<\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u201cMe dou o direto de recusar servi\u00e7o a qualquer pessoa\u201d.&nbsp;No dia em que li esta frase, no fim de 2013, aos 36 anos, minha vida mudou completamente. O primeiro passo em dire\u00e7\u00e3o aos em dire\u00e7\u00e3o aos meus sonhos. Quatro meses antes, no dia 1 de setembro, eu viajava para Nova York. Cinco dias depois iria [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4227,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[116],"tags":[],"class_list":["post-1133","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transicao-de-carreira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje<\/title>\n<meta name=\"description\" content=\"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje\" \/>\n<meta property=\"og:description\" content=\"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-15T10:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T16:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/02\/O-dia-perfeito-e-hoje-primeiro-passo-em-direcao-aos-seus-sonhos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"O dia perfeito \u00e9 hoje: primeiro passo em dire\u00e7\u00e3o aos seus sonhos\",\"datePublished\":\"2016-02-15T10:00:19+00:00\",\"dateModified\":\"2023-03-22T16:47:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\"},\"wordCount\":1950,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Transi\u00e7\u00e3o de carreira\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\",\"name\":\"Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-02-15T10:00:19+00:00\",\"dateModified\":\"2023-03-22T16:47:36+00:00\",\"description\":\"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O dia perfeito \u00e9 hoje: primeiro passo em dire\u00e7\u00e3o aos seus sonhos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje","description":"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/","og_locale":"pt_BR","og_type":"article","og_title":"Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje","og_description":"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.","og_url":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-02-15T10:00:19+00:00","article_modified_time":"2023-03-22T16:47:36+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/02\/O-dia-perfeito-e-hoje-primeiro-passo-em-direcao-aos-seus-sonhos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/"},"author":{"name":"","@id":""},"headline":"O dia perfeito \u00e9 hoje: primeiro passo em dire\u00e7\u00e3o aos seus sonhos","datePublished":"2016-02-15T10:00:19+00:00","dateModified":"2023-03-22T16:47:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/"},"wordCount":1950,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Transi\u00e7\u00e3o de carreira"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/","url":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/","name":"Primeiro passo em dire\u00e7\u00e3o aos seus sonhos: o dia perfeito \u00e9 hoje","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-02-15T10:00:19+00:00","dateModified":"2023-03-22T16:47:36+00:00","description":"Precisamos dar o primeiro passo em dire\u00e7\u00e3o aos seus sonhos. O TGI Today Business Academy \u00e9 para pessoas que sonham em trabalhar com mais significado.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/primeiro-passo-em-direcao-aos-seus-sonhos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O dia perfeito \u00e9 hoje: primeiro passo em dire\u00e7\u00e3o aos seus sonhos"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1133\/revisions"}],"predecessor-version":[{"id":5111,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1133\/revisions\/5111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4227"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1133"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1133"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}