{"id":1574,"date":"2017-05-31T09:00:09","date_gmt":"2017-05-31T12:00:09","guid":{"rendered":"http:\/\/tgitoday.com.br\/?p=1574"},"modified":"2023-03-22T09:58:36","modified_gmt":"2023-03-22T12:58:36","slug":"dizer-nao","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/","title":{"rendered":"Dizer n\u00e3o: o mundo precisa de mais negativas"},"content":{"rendered":"\n<p>Por que dizer n\u00e3o \u00e9 t\u00e3o desafiador? Como dizer n\u00e3o aos outros sem mago\u00e1-los? Por que nos preocupamos mais em respeitar o outro do que a n\u00f3s pr\u00f3prios?<\/p>\n\n\n\n<p>Voc\u00ea, assim&nbsp;como eu, j\u00e1 jogou muito TETRIS. Outro dia recebi pelo WhatsApp a seguinte mensagem: \u201cQuando voc\u00ea tenta se encaixar, voc\u00ea desaparece\u201d. Incr\u00edvel, esse foi o insight que eu precisava para escrever este texto. <\/p>\n\n\n\n<p>Em uma noite fria, junto com algumas amigas, fal\u00e1vamos sobre a nossa <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/aprenda-dizer-nao\/\" target=\"_blank\" rel=\"noreferrer noopener\">dificuldade em dizer n\u00e3o<\/a>. O quanto os outros invadem nossos espa\u00e7os e com isso faz com que perdamos nosso poder pessoal. Nos sentimos fragilizados e sem energia, at\u00e9 mesmo tristes por n\u00e3o conseguirmos delimitar aquela barreira que precisaria ser colocada.<\/p>\n\n\n\n<p>Separei 3 dicas super pr\u00e1ticas para voc\u00ea come\u00e7ar a dizer n\u00e3o sem sentir culpa! D\u00ea play no v\u00eddeo e comece hoje a abrir espa\u00e7o para novas oportunidades!<\/p>\n\n\n\n<figure>\n<iframe title=\"COMO DIZER N\u00c3O SEM SENTIR CULPA?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hOsWLPIQ1_U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o limite da permissividade?<\/h2>\n\n\n\n<p>Vivemos tentando nos encaixar em padr\u00f5es, em estere\u00f3tipos, em pensamentos viciados e esquecemos de cultivar nossa pr\u00f3pria personalidade. Mas chega um certo momento em que tudo isso torna-se insustent\u00e1vel!<\/p>\n\n\n\n<p>O <a href=\"https:\/\/ligiacosta.com.br\/blog\/superar-o-medo-do-fracasso\/\" target=\"_blank\" rel=\"noreferrer noopener\">medo<\/a> do julgamento do outro, o medo de sermos exclu\u00eddos, o medo de n\u00e3o agradarmos, o medo de n\u00e3o sermos aceitos, o medo de falarem mal da gente&#8230; Enfim: o medo do n\u00e3o pertencimento. <\/p>\n\n\n\n<p>O medo nos torna permiss\u00edveis. O medo nos paralisa e sem perceber, mais uma vez, dissemos sim querendo ter dito n\u00e3o!<\/p>\n\n\n\n<p>O limite da permissividade \u00e9 individual e deve estar totalmente de acordo com os seus sentimentos. Observe e coloque limites sempre que perceber um desconforto.<\/p>\n\n\n\n<p>Preste aten\u00e7\u00e3o na sua intui\u00e7\u00e3o (aquele primeiro pensamento, a rea\u00e7\u00e3o instintiva que voc\u00ea teve) nas sensa\u00e7\u00f5es f\u00edsicas: o cora\u00e7\u00e3o que dispara, o n\u00f3 na garganta, a m\u00e3o gelada, o suor, as express\u00f5es faciais&#8230; Perceba que se algo diferente aconteceu, alguma coisa n\u00e3o est\u00e1 certa.<\/p>\n\n\n\n<p>Este \u00e9 o seu limite. Nesta hora voc\u00ea deve dizer n\u00e3o! Cuidado para que o medo em <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/multipotencialidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">assumir a sua pr\u00f3pria verdade<\/a>&nbsp;n\u00e3o fa\u00e7a de voc\u00ea mais uma pe\u00e7a do tetris, que desaparece ao encaixar-se perfeitamente em todas as outras.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dizer sim pode lev\u00e1-lo ao fracasso!<\/h2>\n\n\n\n<p>Dizer sim n\u00e3o far\u00e1 de voc\u00ea mais legal, mais popular, mais aceito ou mais bem sucedido. Pelo contr\u00e1rio, voc\u00ea continuar\u00e1 sendo julgado, comparado e falado.&nbsp;Como disse Einstein em sua teoria da relatividade: tudo depende do ponto de refer\u00eancia.<\/p>\n\n\n\n<p>Este, sim, nos enfraquece, nos distancia de n\u00f3s mesmos, das nossas verdades, das nossas cren\u00e7as, da <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/o-dia-perfeito-e-hoje\/\" target=\"_blank\" rel=\"noreferrer noopener\">nossa miss\u00e3o<\/a>, das nossas caracter\u00edsticas. Ele&nbsp;pode nos deixar vulner\u00e1vel, pois assinamos um contrato de desacordo com n\u00f3s mesmos.<\/p>\n\n\n\n<p>O sim e o n\u00e3o s\u00e3o subjetivos, assim como a beleza e o gosto s\u00e3o subjetivos. E se tudo depende do ponto de refer\u00eancia, neste caso, a referencia \u00e9 apenas voc\u00ea, seu car\u00e1ter, sua autenticidade e o resgate do seu poder pessoal.&nbsp;Pratique o n\u00e3o e comece agora!<\/p>\n\n\n\n<p>Dizer n\u00e3o aos outros \u00e9 resgatar do fundo do seu cora\u00e7\u00e3o aquilo que voc\u00ea acredita, o seu brilho, a sua \u00e9tica e os seus valores. Se algu\u00e9m n\u00e3o gostar, tudo bem, somos todos seres humanos em constante evolu\u00e7\u00e3o e cada um interpretar\u00e1 da maneira que melhor lhe convier.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A quem devo dizer n\u00e3o?<\/h2>\n\n\n\n<p>Diga n\u00e3o aos seus filhos. Eles v\u00e3o entender que existem limites a serem respeitados. Explique apenas para voc\u00eas mesmo o que \u00e9 certo e errado, n\u00e3o aos outros.<\/p>\n\n\n\n<p>Diga n\u00e3o aos seus amigos. Eles v\u00e3o admir\u00e1-lo pela sua clareza. Mas isto n\u00e3o significa que voc\u00ea estar\u00e1 livre de julgamentos.<\/p>\n\n\n\n<p>Diga n\u00e3o&nbsp;ao seu <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/gestao-humanizada\/\" target=\"_blank\" rel=\"noreferrer noopener\">chefe<\/a>. Ele o respeitar\u00e1 pelos seus valores.<\/p>\n\n\n\n<p>Diga n\u00e3o aos&nbsp;seus pais. Eles talvez n\u00e3o entendam, mas v\u00e3o respeitar que voc\u00ea cresceu e assumiu sua personalidade adulta.<\/p>\n\n\n\n<p>Diga n\u00e3o aos seus funcion\u00e1rios. Eles v\u00e3o descobrir que existem regras e processos a serem cumpridos.<\/p>\n\n\n\n<p>Diga n\u00e3o aos seus clientes. Eles v\u00e3o descobrir que voc\u00ea \u00e9 \u00e9tico e profissional e que <a style=\"color: #82a892;\" href=\"https:\/\/ligiacosta.com.br\/blog\/novos-consumidores\/\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o faz qualquer coisa por dinheiro.<\/a>&nbsp;<\/p>\n\n\n\n<p>Diga n\u00e3o \u00e0 <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/presidente-da-sua-republica\/\" target=\"_blank\" rel=\"noreferrer noopener\">corrup\u00e7\u00e3o<\/a>. Aos poucos, a \u00e9tica.<\/p>\n\n\n\n<p>Diga n\u00e3o ao seu ego. Ele vai brigar, espernear, mas, aos poucos, ele vai ajudar voc\u00ea a entender que n\u00e3o \u00e9 o dono da verdade.<\/p>\n\n\n\n<p>Diga n\u00e3o ao seu pr\u00f3prio julgamento para com os outros, s\u00f3 assim voc\u00ea ter\u00e1 compaix\u00e3o pelo pr\u00f3ximo.<\/p>\n\n\n\n<p>Descubra que&nbsp;o n\u00e3o \u00e9 a palavra mais libertadora do mundo!<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Equil\u00edbrio \u00e9 a chave<\/h2>\n\n\n\n<p>E o que fazer quando sentimos uma vontade absurda em dizer n\u00e3o e impor limites ao que nos sufocam? Fa\u00e7a o que a sua intui\u00e7\u00e3o disser!<\/p>\n\n\n\n<p>E aprender a dar negativas n\u00e3o significa que voc\u00ea nunca mais poder\u00e1 dizer que sim. Como no filme &#8220;Sim, senhor&#8221;, a mensagem mais importante aprendida pelo personagem de Jim Carrey \u00e9 que \u00e9 necess\u00e1rio aprender a filtrar as oportunidades e saber o que priorizar em determinado momento!<\/p>\n\n\n\n<p>E voc\u00ea? J\u00e1 disse algum n\u00e3o hoje? Conta para mim nos coment\u00e1rios, vou adorar ler a sua hist\u00f3ria!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e1tica Gratuita de Aten\u00e7\u00e3o Plena<\/h2>\n\n\n\n<p>Desenvolva sua aten\u00e7\u00e3o plena hoje! Clique aqui e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/pratica-atencao-plena-opt-in\" target=\"_blank\" rel=\"noreferrer noopener\">baixe gratuitamente<\/a> nossa pr\u00e1tica de aten\u00e7\u00e3o plena.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Por que dizer n\u00e3o \u00e9 t\u00e3o desafiador? Como dizer n\u00e3o aos outros sem mago\u00e1-los? Por que nos preocupamos mais em respeitar o outro do que a n\u00f3s pr\u00f3prios? Voc\u00ea, assim&nbsp;como eu, j\u00e1 jogou muito TETRIS. Outro dia recebi pelo WhatsApp a seguinte mensagem: \u201cQuando voc\u00ea tenta se encaixar, voc\u00ea desaparece\u201d. Incr\u00edvel, esse foi o insight [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4077,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118],"tags":[],"class_list":["post-1574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-emocional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-31T12:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T12:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/05\/Dizer-nao-o-mundo-precisa-de-mais-negativas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dizer n\u00e3o: o mundo precisa de mais negativas\",\"datePublished\":\"2017-05-31T12:00:09+00:00\",\"dateModified\":\"2023-03-22T12:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\"},\"wordCount\":936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Intelig\u00eancia emocional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\",\"name\":\"Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2017-05-31T12:00:09+00:00\",\"dateModified\":\"2023-03-22T12:58:36+00:00\",\"description\":\"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dizer n\u00e3o: o mundo precisa de mais negativas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa","description":"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/","og_locale":"pt_BR","og_type":"article","og_title":"Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa","og_description":"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!","og_url":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/","og_site_name":"Blog Ligia Costa","article_published_time":"2017-05-31T12:00:09+00:00","article_modified_time":"2023-03-22T12:58:36+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/05\/Dizer-nao-o-mundo-precisa-de-mais-negativas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/"},"author":{"name":"","@id":""},"headline":"Dizer n\u00e3o: o mundo precisa de mais negativas","datePublished":"2017-05-31T12:00:09+00:00","dateModified":"2023-03-22T12:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/"},"wordCount":936,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Intelig\u00eancia emocional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/","url":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/","name":"Dizer n\u00e3o: o mundo precisa de mais negativas - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2017-05-31T12:00:09+00:00","dateModified":"2023-03-22T12:58:36+00:00","description":"Ser\u00e1 que precisamos mesmo aceitar tudo o que acontece ou temos a op\u00e7\u00e3o de dizer n\u00e3o a algumas coisas? Vem descobrir como dizer n\u00e3o com o TGI Today!","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Dizer n\u00e3o: o mundo precisa de mais negativas"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1574"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1574\/revisions"}],"predecessor-version":[{"id":4741,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1574\/revisions\/4741"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4077"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}