{"id":1613,"date":"2017-06-21T21:41:07","date_gmt":"2017-06-22T00:41:07","guid":{"rendered":"http:\/\/tgitoday.com.br\/?p=1613"},"modified":"2023-03-22T09:51:24","modified_gmt":"2023-03-22T12:51:24","slug":"buscar-empreendedorismo-com-proposito","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/","title":{"rendered":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito"},"content":{"rendered":"\n<p>\u201cEstou mais motivada, entusiasmada com as novas experi\u00eancias, tenho vontade de levantar da cama e ir trabalhar e ver a evolu\u00e7\u00e3o do meu neg\u00f3cio. Antes n\u00e3o tinha nada disso, era totalmente desmotivada e sem prazer nenhum em fazer o que fazia. Sem perspectivas de futuro no meu emprego.\u201d&nbsp;Estas foram as palavras de L\u00edvia Galhardo, fundadora da \u00f3tica Home \u00d3culos, quando perguntei qual foi a maior mudan\u00e7a que ela percebeu em sua vida depois de buscar um empreendedorismo com prop\u00f3sito com a ajuda do <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/business-academy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Business Academy<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A preocupa\u00e7\u00e3o com a sa\u00fade ao buscar empreendedorismo com prop\u00f3sito<\/h2>\n\n\n\n<p>Ainda que estivesse insatisfeita com o emprego atual \u00e0 \u00e9poca, o grande respons\u00e1vel por fazer com que L\u00edvia procurasse um trabalho que lhe trouxesse mais satisfa\u00e7\u00e3o foi o tr\u00e2nsito. \u201cTudo come\u00e7ou quando me mudei para um bairro distante do meu antigo trabalho. Al\u00e9m do <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/clareza-e-foco-com-a-meditacao\/\" target=\"_blank\" rel=\"noreferrer noopener\">estresse do trabalho<\/a>, tinha tamb\u00e9m o estresse do tr\u00e2nsito. Coloquei na minha cabe\u00e7a que se eu n\u00e3o mudasse agora, poderia adoecer e acabar com o relacionamento com meu noivo\u201d, explica ela.<\/p>\n\n\n\n<p>L\u00edvia come\u00e7ou a pensar em buscar empreendedorismo com prop\u00f3sito a partir de um ponto de partida que \u00e9 muito comum. A preocupa\u00e7\u00e3o com a qualidade de vida. Quando nos imaginamos felizes e realizados, \u00e9 muito dif\u00edcil incluir nesse cen\u00e1rio de satisfa\u00e7\u00e3o horas desperdi\u00e7adas dentro do carro para ir de um lugar a outro.<\/p>\n\n\n\n<p>E a troca de endere\u00e7o foi apenas o catalizador da necessidade de mudan\u00e7a para ela. Que j\u00e1 sentia os n\u00edveis de ansiedade mais altos h\u00e1 algum tempo. \u201cVivia infeliz e ansiosa por n\u00e3o saber o que fazer da vida. N\u00e3o sabia se continuava com o meu trabalho de optometria que eu j\u00e1 exercia h\u00e1 alguns anos, mas que n\u00e3o me agradava mais, ou se mudava de emprego e fazia algo que realmente me desse prazer\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A compensat\u00f3ria jornada de empreender<\/h2>\n\n\n\n<p>E acabou que a necessidade de aproveitar mais e melhor o seu tempo, al\u00e9m da vontade de buscar empreendedorismo com prop\u00f3sito e novos desafios e possibilidades na vida, fez com que a L\u00edvia optasse por se arriscar no mundo do empreendedorismo, mesmo que o <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superar-o-medo-do-fracasso\/\" target=\"_blank\" rel=\"noreferrer noopener\">medo de falhar<\/a> ainda a acompanhasse.<\/p>\n\n\n\n<p>&#8220;O medo de n\u00e3o dar certo foi meu principal empecilho. De trocar o certo pelo duvidoso. Mas penso que se n\u00e3o tentarmos nunca saberemos se dar\u00e1 certo. Por isso resolvi arriscar e ainda estou arriscando todas as minhas fichas nesse projeto\u201d, conta ela.<\/p>\n\n\n\n<p>E quando a inseguran\u00e7a e a incerteza de qual era o pr\u00f3ximo passo apareceram, ela soube que precisava buscar orienta\u00e7\u00f5es de como fazer com que a sua felicidade se materializasse na forma do neg\u00f3cio pr\u00f3prio ao buscar empreendedorismo com&nbsp;<a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/trabalhar-com-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">prop\u00f3sito<\/a>.<\/p>\n\n\n\n<p>\u201cProcurei o Business Academy num momento muito dif\u00edcil de indecis\u00f5es, incertezas e medos. O curso foi bom para abrir minha mente, clarear minhas id\u00e9ias e me fazer sentir uma imensa vontade de mudar de vida e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/sonhos-e-metas-de-sua-vida\/\" target=\"_blank\" rel=\"noreferrer noopener\">me realizar profissionalmente<\/a>\u201d. A troca de ideias comigo e com os outros alunos da turma da qual participou tamb\u00e9m foram fatores decisivos para a L\u00edvia. Ver as experi\u00eancias dos outros fez com que ela n\u00e3o se sentisse mais sozinha em suas d\u00favidas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Prop\u00f3sito &gt; Lucro<\/h2>\n\n\n\n<p>E tudo isso fez com que a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/www.homeoculos.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">Home \u00d3culos<\/a> sa\u00edsse do papel e se tornasse a realidade profissional da L\u00edvia. Hoje ela v\u00ea no e-commerce da sua \u00f3tica uma porta aberta para novas oportunidades. Al\u00e9m disso, ela tamb\u00e9m tem em vista a realiza\u00e7\u00e3o de novos projetos, que j\u00e1 est\u00e3o saindo do forno.<\/p>\n\n\n\n<p>Ainda assim, ela acredita que o dinheiro n\u00e3o deve ser a principal for\u00e7a que move o mundo. Para ela, n\u00e3o adianta ter um \u00f3timo sal\u00e1rio se voc\u00ea sai infeliz para trabalhar todos os dias. \u201cEstou super animada com tudo. Temos que colocar na cabe\u00e7a que <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/negocio-com-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o importa o quanto de dinheiro voc\u00ea ganha no seu trabalho<\/a>. Claro que \u00e9 importante, mas n\u00e3o \u00e9 fundamental\u201d, comenta ela.<\/p>\n\n\n\n<p>\u00c9 importante redefinirmos nossas prioridades e pesarmos se realmente vale a pena sentir que n\u00e3o tem <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/hoje-e-o-dia-ideal-para-voce-comecar-viver-com-mais-significado\/\" target=\"_blank\" rel=\"noreferrer noopener\">um significado maior na vida<\/a>. Mesmo que sua situa\u00e7\u00e3o financeira esteja muito bem. \u201cSe voc\u00ea tiver que passar uma vida fazendo algo que n\u00e3o te agrada, voc\u00ea ser\u00e1 muito infeliz. E isso ir\u00e1 influenciar na sua rela\u00e7\u00e3o com outras pessoas, inclusive familiares mais pr\u00f3ximos. Um dia voc\u00ea pode at\u00e9 adoecer e ter\u00e1 que gastar todo o seu dinheiro em rem\u00e9dios. At\u00e9 que ponto vale a pena? Fa\u00e7a o que te faz bem que o resto vem\u201d, constata L\u00edvia.<\/p>\n\n\n\n<p>Voc\u00ea pode conhecer a \u00f3tica da L\u00edvia clicando <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/www.homeoculos.com.br\/\" target=\"_blank\" rel=\"noopener noreferrer\">aqui<\/a>!<\/p>\n\n\n\n<p>Gostou de conhecer a hist\u00f3ria de mudan\u00e7a de vida da L\u00edvia? Deixe para mim nos coment\u00e1rios o que est\u00e1 te impedindo hoje de entrar em a\u00e7\u00e3o!&nbsp;<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Minicurso Gratuito<\/h2>\n\n\n\n<p>Comece agora!&nbsp;<a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/minicurso-proposito-assistir\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Inscreva-se<\/strong><\/a><strong>&nbsp;no minicurso gratuito Prop\u00f3sito: 5 passos para ter um trabalho com significado.<\/strong>&nbsp;Nele voc\u00ea ter\u00e1 a oportunidade de iniciar o seu processo, um primeiro passo que poder\u00e1 gerar clareza e ao mesmo tempo curiosidade para um mundo de infinitas possibilidades.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>\u201cEstou mais motivada, entusiasmada com as novas experi\u00eancias, tenho vontade de levantar da cama e ir trabalhar e ver a evolu\u00e7\u00e3o do meu neg\u00f3cio. Antes n\u00e3o tinha nada disso, era totalmente desmotivada e sem prazer nenhum em fazer o que fazia. Sem perspectivas de futuro no meu emprego.\u201d&nbsp;Estas foram as palavras de L\u00edvia Galhardo, fundadora [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,117],"tags":[],"class_list":["post-1613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito","category-gente-que-inspira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-22T00:41:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T12:51:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/06\/Home-Oculos-um-case-de-empreendedorismo-com-proposito.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito\",\"datePublished\":\"2017-06-22T00:41:07+00:00\",\"dateModified\":\"2023-03-22T12:51:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\"},\"wordCount\":906,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\",\"Gente que inspira\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\",\"name\":\"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2017-06-22T00:41:07+00:00\",\"dateModified\":\"2023-03-22T12:51:24+00:00\",\"description\":\"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa","description":"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/","og_locale":"pt_BR","og_type":"article","og_title":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa","og_description":"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito","og_url":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/","og_site_name":"Blog Ligia Costa","article_published_time":"2017-06-22T00:41:07+00:00","article_modified_time":"2023-03-22T12:51:24+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/06\/Home-Oculos-um-case-de-empreendedorismo-com-proposito.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/"},"author":{"name":"","@id":""},"headline":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito","datePublished":"2017-06-22T00:41:07+00:00","dateModified":"2023-03-22T12:51:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/"},"wordCount":906,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito","Gente que inspira"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/","url":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/","name":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2017-06-22T00:41:07+00:00","dateModified":"2023-03-22T12:51:24+00:00","description":"Saiba como a empreendedora L\u00edvia Galhardo conseguiu aumentar a sua qualidade de vida e satisfa\u00e7\u00e3o pessoal ao buscar empreendedorismo com prop\u00f3sito","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Home \u00d3culos: um case de empreendedorismo com prop\u00f3sito"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1613"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1613\/revisions"}],"predecessor-version":[{"id":4721,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1613\/revisions\/4721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4069"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}