{"id":1667,"date":"2017-08-02T00:29:30","date_gmt":"2017-08-02T03:29:30","guid":{"rendered":"http:\/\/tgitoday.com.br\/?p=1667"},"modified":"2023-03-22T09:45:40","modified_gmt":"2023-03-22T12:45:40","slug":"lideranca-servidora-no-seu-negocio","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/","title":{"rendered":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida"},"content":{"rendered":"\n<p>Queria compartilhar com voc\u00eas essas mudan\u00e7as que a lideran\u00e7a servidora pode trazer \u00e0 sua vida. Mas antes&nbsp;vou falar um pouco sobre o que as pessoas ainda enxergam como boa lideran\u00e7a.<\/p>\n\n\n\n<p>\u00c9 super normal pensar em alguns perfis bem espec\u00edficos quando o assunto \u201clideran\u00e7a\u201d surge nas rodas de conversa, palestras ou encontros. Muitas pessoas, incluindo gestores e funcion\u00e1rios, acreditam que para ser respeitado como l\u00edder \u00e9 preciso ter uma postura inflex\u00edvel, autorit\u00e1ria e exigente.<\/p>\n\n\n\n<p>E apesar das <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/o-que-mudou-nos-ultimos-dez-anos\/\" target=\"_blank\" rel=\"noreferrer noopener\">muitas transforma\u00e7\u00f5es pelas quais o mundo passou nos \u00faltimos anos<\/a>, essa no\u00e7\u00e3o do que \u00e9 ser um bom l\u00edder e gestor se mant\u00e9m ainda forte em muitas empresas e espa\u00e7os de trabalho.<\/p>\n\n\n\n<p>Al\u00e9m dessa <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/gestao-humanizada\/\" target=\"_blank\" rel=\"noreferrer noopener\">defini\u00e7\u00e3o de bom l\u00edder<\/a>, a cren\u00e7a de que existem pessoas que nascem com um \u201cdom\u201d de comandar e que somente elas poderiam gerir bem \u00e9 outro mito que se mant\u00e9m no universo corporativo e empreendedor.<\/p>\n\n\n\n<p>\u00c9 claro que existem aqueles que s\u00e3o conhecidos como \u201cl\u00edderes natos\u201d, que t\u00eam como tra\u00e7os de personalidade o tato e o traquejo para lidar com pessoas. Mas n\u00e3o s\u00e3o somente eles que podem ser considerados aptos para serem bons gestores.<\/p>\n\n\n\n<p>Habilidades de lideran\u00e7a podem ser desenvolvidas ao longo do tempo. E mais do que isso. \u00c9 poss\u00edvel aprender uma nova forma de comandar que vise n\u00e3o somente a organiza\u00e7\u00e3o do seu neg\u00f3cio, mas um impacto positivo pessoal, profissional, individual, coletivo e social: uma lideran\u00e7a servidora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que lideran\u00e7a servidora?<\/h2>\n\n\n\n<p>Acho que \u00e9 este ponto pelo qual voc\u00ea estava esperando. \u201cComo essa lideran\u00e7a servidora pode mudar tanto assim a forma como eu enxergo meu neg\u00f3cio, minha equipe e at\u00e9 a mim mesmo?\u201d, voc\u00ea deve estar se perguntando.<\/p>\n\n\n\n<p>O conceito de lideran\u00e7a servidora \u00e9 permeado por todos os pilares positivos que j\u00e1 existiam na defini\u00e7\u00e3o do que \u00e9 liderar, como boa gest\u00e3o, organiza\u00e7\u00e3o, compreens\u00e3o, etc.. Mas inclu\u00ed um novo alicerce que pode ajudar voc\u00ea a enxergar al\u00e9m da gest\u00e3o: a import\u00e2ncia de impactar positivamente o mundo ao seu redor.<\/p>\n\n\n\n<p>Ser um l\u00edder servidor significa que a sua atua\u00e7\u00e3o profissional n\u00e3o gira em torno apenas da sua empresa e de voc\u00ea mesmo. Significa que voc\u00ea d\u00e1 a devida import\u00e2ncia para o que a sua profiss\u00e3o e o seu empreendimento podem trazer de positivo \u00e0 sociedade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A lideran\u00e7a servidora na sua vida<\/h2>\n\n\n\n<p>Liderar o seu empreendimento e servir a um prop\u00f3sito maior simultaneamente \u00e9 super poss\u00edvel. E nem de longe \u00e9 t\u00e3o dif\u00edcil quanto parece. Isso porque, cada vez mais, as empresas, corpora\u00e7\u00f5es e neg\u00f3cios <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/negocio-com-proposito\/\">est\u00e3o levando em conta muito mais do que o lucro.<\/a> Consideram tamb\u00e9m o seu impacto social e ambiental, al\u00e9m de buscarem sempre um ambiente saud\u00e1vel para seus funcion\u00e1rios e clientes.<\/p>\n\n\n\n<p>Aplicar esse novo conceito no seu dia a dia de trabalho pode ser a mudan\u00e7a que voc\u00ea precisava para conseguir a inova\u00e7\u00e3o que tanto buscava. Ainda que ela parecesse estar distante da sua realidade atual.<\/p>\n\n\n\n<p>Come\u00e7ar a considerar como prioridade a forma como voc\u00ea impacta o que est\u00e1 ao seu redor. Isso \u00e9 uma outra forma de dizer que voc\u00ea est\u00e1 <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/4-passos-para-viver-com-mais-proposito\/\">vivendo com mais prop\u00f3sito<\/a>. E empreender e trabalhar com prop\u00f3sito d\u00e1 um novo e maior significado \u00e0 sua vida e \u00e0 sua profiss\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>3 Dicas para voc\u00ea come\u00e7ar a colocar em pr\u00e1tica sua lideran\u00e7a a partir de hoje:<\/strong><\/h2>\n\n\n\n<p><strong>1-) Seja um bom ouvinte!<\/strong> Ou\u00e7a sem julgamento, apenas dedique o seu tempo para praticar a escuta ativa e compreender as necessidades da sua equipe e das pessoas que precisam da sua ajuda!<\/p>\n\n\n\n<p><strong>2-) Esteja Presente!<\/strong> A partir do momento que voc\u00ea escolher fazer parte de um projeto, estar em uma reuni\u00e3o, seja colaborativo e participe!<\/p>\n\n\n\n<p><strong>3-) N\u00e3o \u00e9 sobre voc\u00ea, mas sim como voc\u00ea pode impactar o outro!<\/strong> Como l\u00edder, seu papel \u00e9 ajudar nos bastidores e servir para que os processos e as metas sejam atingidas! <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Torne-se um agente de transforma\u00e7\u00e3o<\/h2>\n\n\n\n<p>Sabe aquela frase \u201cseja a mudan\u00e7a que voc\u00ea quer ver no mundo\u201d? Quantas vezes voc\u00ea n\u00e3o se sentiu frustrado com alguma empresa que n\u00e3o considerava a experi\u00eancia do cliente? Cabem na sua m\u00e3o \u00e0s vezes em que o produto ou servi\u00e7o entregue estava longe do esperado?<\/p>\n\n\n\n<p>Por qu\u00ea n\u00e3o voc\u00ea a ser aquele que vai fazer diferente? Aquele que trabalha para alinhar o empreendedorismo com prop\u00f3sito, a lideran\u00e7a servidora e a experi\u00eancia do seu cliente? E voc\u00ea pode come\u00e7ar agora!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Pr\u00e1tica Gratuita de Aten\u00e7\u00e3o Plena<\/h2>\n\n\n\n<p>Desenvolva sua aten\u00e7\u00e3o plena hoje! Clique aqui e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/pratica-atencao-plena-opt-in\" target=\"_blank\" rel=\"noreferrer noopener\">baixe gratuitamente<\/a> nossa pr\u00e1tica de aten\u00e7\u00e3o plena.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Queria compartilhar com voc\u00eas essas mudan\u00e7as que a lideran\u00e7a servidora pode trazer \u00e0 sua vida. Mas antes&nbsp;vou falar um pouco sobre o que as pessoas ainda enxergam como boa lideran\u00e7a. \u00c9 super normal pensar em alguns perfis bem espec\u00edficos quando o assunto \u201clideran\u00e7a\u201d surge nas rodas de conversa, palestras ou encontros. Muitas pessoas, incluindo gestores [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4066,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-1667","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lideranca-humanizada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-02T03:29:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T12:45:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/08\/Descubra-como-a-lideranca-servidora-pode-mudar-a-sua-vida.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Descubra como a lideran\u00e7a servidora pode mudar a sua vida\",\"datePublished\":\"2017-08-02T03:29:30+00:00\",\"dateModified\":\"2023-03-22T12:45:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\"},\"wordCount\":817,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Lideran\u00e7a humanizada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\",\"name\":\"Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2017-08-02T03:29:30+00:00\",\"dateModified\":\"2023-03-22T12:45:40+00:00\",\"description\":\"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descubra como a lideran\u00e7a servidora pode mudar a sua vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa","description":"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/","og_locale":"pt_BR","og_type":"article","og_title":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa","og_description":"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!","og_url":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/","og_site_name":"Blog Ligia Costa","article_published_time":"2017-08-02T03:29:30+00:00","article_modified_time":"2023-03-22T12:45:40+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/08\/Descubra-como-a-lideranca-servidora-pode-mudar-a-sua-vida.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/"},"author":{"name":"","@id":""},"headline":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida","datePublished":"2017-08-02T03:29:30+00:00","dateModified":"2023-03-22T12:45:40+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/"},"wordCount":817,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Lideran\u00e7a humanizada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/","url":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/","name":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2017-08-02T03:29:30+00:00","dateModified":"2023-03-22T12:45:40+00:00","description":"Saiba como a lideran\u00e7a servidora pode mudar a sua rela\u00e7\u00e3o com o seu trabalho e seu prop\u00f3sito, fazendo com que voc\u00ea seja um agente transformador!","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/lideranca-servidora-no-seu-negocio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Descubra como a lideran\u00e7a servidora pode mudar a sua vida"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1667"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1667\/revisions"}],"predecessor-version":[{"id":4702,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1667\/revisions\/4702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4066"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}