{"id":1678,"date":"2017-08-10T20:41:25","date_gmt":"2017-08-10T23:41:25","guid":{"rendered":"http:\/\/tgitoday.com.br\/?p=1678"},"modified":"2023-04-20T15:33:09","modified_gmt":"2023-04-20T18:33:09","slug":"colocar-seus-planos-em-acao","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/","title":{"rendered":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o"},"content":{"rendered":"\n<p>Sentir inseguran\u00e7a na hora de tomar decis\u00f5es importantes faz parte da vida. E ter dificuldades na hora de colocar seus planos em a\u00e7\u00e3o \u00e9 totalmente normal. Isso porque fazer uma escolha sempre significa que algo precisa ser deixado de lado.<\/p>\n\n\n\n<p>O mundo mudou, est\u00e1 cada vez mais r\u00e1pido, vol\u00e1til, incerto e amb\u00edguo, nem por isso podemos deixar de lado nossos sonhos e ideais. Neste cen\u00e1rio complexo, que \u00e9 a realidade da atualidade \u00e9 exigido de n\u00f3s protagonismo e presen\u00e7a.<\/p>\n\n\n\n<p>Neste v\u00eddeo eu falo um pouco mais desse mundo, veja o que voc\u00ea acha de tudo isso e me conte como vai enfrentar esse momento.<\/p>\n\n\n\n<figure>\n<iframe title=\"Mundo VUCA: o que \u00e9 e como ele afeta voc\u00ea?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/nTPl4J2nPDY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<p>Mas sentir todas essas coisas nunca deve impedir que voc\u00ea trilhe seu caminho e busque seus sonhos.<\/p>\n\n\n\n<p>Ter medo de falhar n\u00e3o pode segurar voc\u00ea sempre no mesmo lugar. Nem sempre a estabilidade em um trabalho que voc\u00ea n\u00e3o gosta trar\u00e1 felicidade. \u00c0s vezes \u00e9 preciso <a href=\"https:\/\/ligiacosta.com.br\/blog\/trabalhar-com-proposito\/\">buscar prop\u00f3sito<\/a> em novos desafios e empreitadas.<\/p>\n\n\n\n<p>Foi o que aconteceu com a Livia Galhardo, fundadora da Home \u00d3culos. \u201cO medo de n\u00e3o dar certo foi meu principal empecilho.<\/p>\n\n\n\n<p>O medo de trocar o certo pelo duvidoso. Mas penso que se n\u00e3o tentarmos nunca saberemos se dar\u00e1 certo\u201d. Contei um pouco mais da <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/buscar-empreendedorismo-com-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">hist\u00f3ria dela e do seu empreendimento aqui.<\/a><\/p>\n\n\n\n<p>A autossabotagem \u00e9 um dos principais empecilhos no caminho de quem deseja colocar seus planos em a\u00e7\u00e3o. N\u00e3o acreditar em si mesmo e em seu potencial impede muitas pessoas de <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/metas-ajudam-um-sonhador-tornar-se-em-um-eficiente-realizador\/\">realizar seus sonhos<\/a>.<\/p>\n\n\n\n<p>Voc\u00ea com certeza j\u00e1 sentiu que n\u00e3o era bom ou capaz o suficiente para realizar um desejo ou conquistar algo? Isso \u00e9 autossabotagem e voc\u00ea pode pratic\u00e1-la de v\u00e1rias formas no seu dia a dia sem nem perceber.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o<\/h2>\n\n\n\n<p>Dentre todas as formas de impedir a si mesmo de conquistar um <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/10-definicoes-de-proposito\/\">novo prop\u00f3sito<\/a> e buscar novos desafios, listei 5 principais que acredito que me afligiram por muito tempo.<\/p>\n\n\n\n<p>\u00c9 delas que voc\u00ea precisa se esquivar para colocar seus planos em a\u00e7\u00e3o agora.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">1) Alto n\u00edvel de exig\u00eancia<\/h3>\n\n\n\n<p>N\u00e3o <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/dizer-nao\/\" target=\"_blank\" rel=\"noreferrer noopener\">conhecer os pr\u00f3prios limites<\/a> e exigir demais de si mesmo. Este \u00e9 um dos erros mais cometidos por quem deseja empreender, mudar de vida ou simplesmente colocar seus planos em a\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"COMO DIZER N\u00c3O SEM SENTIR CULPA?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/hOsWLPIQ1_U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Para que voc\u00ea esteja sempre bem e atinja seu potencial, \u00e9 necess\u00e1rio saber at\u00e9 onde voc\u00ea pode ir.<\/p>\n\n\n\n<p>Tenha tamb\u00e9m a no\u00e7\u00e3o de at\u00e9 quais fronteiras a sua ideia ou empreendimento pode se estender. Nunca queira abra\u00e7ar algo em volta do qual seus bra\u00e7os n\u00e3o se fechem.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2) Compara\u00e7\u00e3o com os outros<\/h3>\n\n\n\n<p>Aquele ditado antigo que diz \u201ca grama do vizinho \u00e9 sempre mais verde\u201d \u00e9 o que define este t\u00f3pico.<\/p>\n\n\n\n<p>Nunca parecemos estar satisfeitos com aquilo que temos. E, por causa disso, estamos em constante compara\u00e7\u00e3o com os outros. Eles podem ser colegas de trabalho, amigos e at\u00e9 mesmo familiares.<\/p>\n\n\n\n<p>Queira sempre ser menos como o outro e mais como a si pr\u00f3prio para colocar seus planos em a\u00e7\u00e3o. Cada pessoa \u00e9 um indiv\u00edduo \u00fanico e assim tamb\u00e9m funciona para empreendimentos e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/inovacao-sem-felicidade-nao-e-possivel\/\" target=\"_blank\" rel=\"noreferrer noopener\">neg\u00f3cios com prop\u00f3sito<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3) Achar que \u00e9 velho demais para come\u00e7ar<\/h3>\n\n\n\n<p>A idade muitas vezes \u00e9 um obst\u00e1culo, especialmente quando falamos em come\u00e7ar algo novo.<\/p>\n\n\n\n<p>Isso porque, para muitas pessoas, a palavra \u201cnovo\u201d \u00e9 sin\u00f4nimo de \u201carriscado\u201d. E nem todo mundo acha que arriscar-se em algo diferente \u00e9 uma coisa boa.<\/p>\n\n\n\n<p><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/idade-certa-para-empreender\/\">Nunca se \u00e9 velho demais para come\u00e7ar a escrever uma nova hist\u00f3ria<\/a>, gerir um novo neg\u00f3cio ou buscar um novo prop\u00f3sito em sua vida. Tudo isso pode acontecer quando voc\u00ea consegue colocar seus planos em a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Eu mesma j\u00e1 n\u00e3o tinha mais 20 anos quando precisei encarar <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/fora-do-mundo-corporativo\/\" target=\"_blank\" rel=\"noreferrer noopener\">o impasse da minha primeira demiss\u00e3o.<\/a> Mas decidi que n\u00e3o ia deixar um par de n\u00fameros me impedir de investir em algo que eu gostasse de fazer.<\/p>\n\n\n\n<p>E voc\u00ea tamb\u00e9m pode! N\u00e3o \u00e9 porque j\u00e1 passou dos 30, 40 ou 50 que j\u00e1 trilhou todos os caminhos poss\u00edveis que a vida reservou para voc\u00ea.<\/p>\n\n\n\n<p>N\u00e3o se deixe intimidar pelo que os outros podem achar. Voc\u00ea pode e conseguir\u00e1 colocar seus planos em a\u00e7\u00e3o.<\/p>\n\n\n\n<p>O empreendedor digital Mauro Sato sintetizou bem o que empreender pode significar na sua vida, mesmo quando n\u00e3o se \u00e9 mais t\u00e3o jovem. \u201cO ato [de empreender] abre a possibilidade de realizar algo com significado, que possa ser uma contribui\u00e7\u00e3o real, um legado para a vida, ajudando outras pessoas\u201d, explica ele.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">4) Falta de tempo<\/h3>\n\n\n\n<p>Parece que a principal moeda de troca do s\u00e9culo 21 agora n\u00e3o \u00e9 mais o dinheiro, mas, sim, o tempo. Sentir que a rotina nos esmaga e que nunca conseguir\u00edamos encaixar um novo empreendimento em meio \u00e0s tarefas \u00e9 comum.<\/p>\n\n\n\n<p>Mas isso n\u00e3o significa que seja verdade. <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/empreendedorismo-e-maternidade\/\">A falta de tempo \u00e9 uma das dificuldades mais comumente enfrentadas por m\u00e3es empreendedoras<\/a>, por exemplo. Mas elas sempre buscam gerenciar bem para que nem um minuto seja desperdi\u00e7ado.<\/p>\n\n\n\n<p>As arquitetas Sabrina Tironi e Daniele Rampasso e a administradora Patrizia Giongo explicaram em um texto que fiz sobre empreendedorismo e maternidade que o fato de o dia parecer n\u00e3o ter horas suficientes para dar conta de tudo \u00e9 um dos principais vil\u00f5es para as mulheres que querem vivenciar empreendedorismo e maternidade.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">5) N\u00e3o pensar no futuro<\/h3>\n\n\n\n<p>Viver um dia de cada vez \u00e9 uma forma de levar a vida mais leve, mas no \u00e2mbito pessoal. Na vida profissional, \u00e9 sempre importante projetar o futuro. E deixar isso de lado \u00e9 um dos principais erros cometidos por quem quer colocar seus planos em a\u00e7\u00e3o.<\/p>\n\n\n\n<p>Enxergue sempre no amanh\u00e3 a possibilidade de colher os resultados plantados hoje. Mas nunca se esque\u00e7a de que <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/o-dia-perfeito-e-hoje\/\">o dia de hoje \u00e9 sempre o melhor dia<\/a> para come\u00e7ar a viver melhor e com mais prop\u00f3sito.<\/p>\n\n\n\n<p>Como bem disse <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/alimente-saude-estrategia-de-marketing\/\">Eduardo Szpak, nutricionista e fundador da Alimente Sa\u00fade<\/a>. \u201cA diferen\u00e7a entre quem somos hoje e quem vamos nos tornar se d\u00e1 em como usamos o agora. Uma hora utilizada diariamente para aprender algo novo ou para desenvolver sua ideia far\u00e1 toda a diferen\u00e7a daqui uns anos\u201d.<\/p>\n\n\n\n<p>Deixe para mim seu coment\u00e1rio e sua hist\u00f3ria de empreendedorismo com prop\u00f3sito, vou adorar l\u00ea-la!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Webin\u00e1rio Gratuito<\/h2>\n\n\n\n<p>Comece agora. Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e Descubra os 4 passos para voc\u00ea equilibrar a sua vida pessoal e profissional, criar metas e focar no que \u00e9 importante. S\u00f3 assim voc\u00ea ter\u00e1 alta performance para minimizar os erros que te impedem de colocar seus planos em a\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Webinar Equil\u00edbrio Alta Performance\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/uNpPyUeqGAs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e em seguida, inscreva-se no curso 100% Online Alta Performance<\/figcaption><\/figure>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Sentir inseguran\u00e7a na hora de tomar decis\u00f5es importantes faz parte da vida. E ter dificuldades na hora de colocar seus planos em a\u00e7\u00e3o \u00e9 totalmente normal. Isso porque fazer uma escolha sempre significa que algo precisa ser deixado de lado. O mundo mudou, est\u00e1 cada vez mais r\u00e1pido, vol\u00e1til, incerto e amb\u00edguo, nem por isso [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4060,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-10T23:41:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-20T18:33:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/08\/5-erros-que-impedem-voce-de-colocar-seus-planos-em-acao.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o\",\"datePublished\":\"2017-08-10T23:41:25+00:00\",\"dateModified\":\"2023-04-20T18:33:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\"},\"wordCount\":1167,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\",\"name\":\"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2017-08-10T23:41:25+00:00\",\"dateModified\":\"2023-04-20T18:33:09+00:00\",\"description\":\"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa","description":"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/","og_locale":"pt_BR","og_type":"article","og_title":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa","og_description":"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!","og_url":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/","og_site_name":"Blog Ligia Costa","article_published_time":"2017-08-10T23:41:25+00:00","article_modified_time":"2023-04-20T18:33:09+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2017\/08\/5-erros-que-impedem-voce-de-colocar-seus-planos-em-acao.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/"},"author":{"name":"","@id":""},"headline":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o","datePublished":"2017-08-10T23:41:25+00:00","dateModified":"2023-04-20T18:33:09+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/"},"wordCount":1167,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/","url":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/","name":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2017-08-10T23:41:25+00:00","dateModified":"2023-04-20T18:33:09+00:00","description":"Descubra quais s\u00e3os os 5 principais erros que voc\u00ea comete que est\u00e3o impedindo voc\u00ea de colocar seus planos em a\u00e7\u00e3o agora para viver com mais prop\u00f3sito!","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/colocar-seus-planos-em-acao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"5 erros que impedem voc\u00ea de colocar seus planos em a\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1678"}],"version-history":[{"count":7,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1678\/revisions"}],"predecessor-version":[{"id":5663,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1678\/revisions\/5663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4060"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}