{"id":1837,"date":"2016-05-04T08:00:08","date_gmt":"2016-05-04T11:00:08","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=622"},"modified":"2023-04-18T17:56:55","modified_gmt":"2023-04-18T20:56:55","slug":"resgatar-sua-lideranca-e-seu-poder-pessoal","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/","title":{"rendered":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal"},"content":{"rendered":"\n<p>Protagonizar o papel de v\u00edtima, n\u00e3o saber onde quer chegar, n\u00e3o ter direcionamento, planejamento e viver sem perspectivas. Ser\u00e1 que pode realmente ser confort\u00e1vel viver sem lideran\u00e7a e poder pessoal?<\/p>\n\n\n\n<p>\u201cMinha meta \u00e9 n\u00e3o ter meta\u201d. Ouvi recentemente essa afirma\u00e7\u00e3o e, em um primeiro momento fiquei desconcertada, mas com alguma reflex\u00e3o lembrei-me de tr\u00eas longos dias de um Workshop que participei h\u00e1 alguns anos, onde o tema em quest\u00e3o era: \u201cLeave people from drama\u201d (Tradu\u00e7\u00e3o livre: Tire pessoas do drama\/v\u00edtima).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">L\u00edderes alimentam o drama<\/h2>\n\n\n\n<p>O aprendizado naquela data tamb\u00e9m me desconsertou. Caiu a minha ficha de que os grandes respons\u00e1veis em alimentarem o drama s\u00e3o os l\u00edderes.&nbsp;\u201c74% da popula\u00e7\u00e3o economicamente ativa no Brasil n\u00e3o tem engajamento\u201d, segundo Raj Sisodia, do Capitalismo Consciente.<\/p>\n\n\n\n<p>Somos inundados por l\u00edderes paternalistas, autorit\u00e1rios, ambiciosos, que alimentam e fomentam a sua volta pessoas dependentes, inseguras, medrosas, servidoras, que apenas cumprem tarefas.<\/p>\n\n\n\n<p>O c\u00edrculo vicioso est\u00e1 formado. O l\u00edder paternalista \u00e9 protetor, tem d\u00f3 e acredita ser soberano, resolve todos os problemas por si s\u00f3, deixando seus subordinados \u201cprotegidos\u201d, sem opini\u00e3o e ap\u00e1ticos. Este l\u00edder alimenta a vitimiza\u00e7\u00e3o, afinal, \u00e9 paternalista.<\/p>\n\n\n\n<p><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/gestao-humanizada\/\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00edderes autorit\u00e1rios alimentam o medo<\/a> e a inseguran\u00e7a, condicionando seus subordinados a oprimirem suas opini\u00f5es. Este l\u00edder alimenta o drama, afinal, \u00e9 autorit\u00e1rio.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Pausa para o futuro ideal desejado<\/h2>\n\n\n\n<p>O l\u00edder contempor\u00e2neo est\u00e1 atento a pessoas, desenvolve empatia e inspira confian\u00e7a, deseja ser exemplo e busca incentivar e motivar o desenvolvimento de seus colaboradores. L\u00edderes, independente do g\u00eanero, tem comportamentos e um poder pessoal cativante.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Empatia no trabalho.  Como ser um li\u0301der que inspira confianc\u0327a?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/dZWAWiCJE4c?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Excesso de vitimiza\u00e7\u00e3o<\/h2>\n\n\n\n<p>Compreendo claramente que os l\u00edderes de hoje n\u00e3o s\u00e3o a refer\u00eancia que o mundo precisa, mas tamb\u00e9m afirmo que a maioria da popula\u00e7\u00e3o se aproveita desta defici\u00eancia para se vitimizar.<\/p>\n\n\n\n<p>Ausentar-se de responsabilidades \u00e9 postergar oportunidades, \u00e9 navegar a deriva, \u00e9 n\u00e3o se apropriar, ou melhor, \u00e9 fugir de si pr\u00f3prio. Gosto muito dessa frase que traz a reflex\u00e3o sobre como equilibrar velhos pensamentos com o mundo atual.<\/p>\n\n\n\n<blockquote class=\"is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p>\u201cOs dogmas do passado n\u00e3o fazem sentido nos dias turbulentos em que vivemos. Nossa causa \u00e9 nova. Precisamos pensar e agir de forma diferente\u201d<\/p>\n\n\n<p>Abraham Lincoln<\/p>\n\n<\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Novo mundo com lideran\u00e7a e poder pessoal<\/h2>\n\n\n\n<p><a href=\"https:\/\/ligiacosta.com.br\/blog\/negocio-com-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">Existe um novo mundo<\/a> e voc\u00ea tem o poder e a escolha em fazer parte dele. Um mundo mais consciente, mais inclusivo, que privilegia um comportamento <em>selfless.<\/em> Cada um de n\u00f3s, todos os dias ao acordar, tem a oportunidade de recome\u00e7ar e inconscientemente faz a sua escolha.<\/p>\n\n\n\n<p>N\u00e3o temos mais tempo para sentar e esperar por l\u00edderes inspiradores. A hora \u00e9 agora. <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/continuar-ou-desistir-o-final-da-sua-historia-quem-decide-e-voce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lidere sua hist\u00f3ria<\/a> e impacte o seu entorno. A mudan\u00e7a come\u00e7a hoje, com voc\u00ea, com a coragem e determina\u00e7\u00e3o em definir e escolher qual caminho voc\u00ea deseja seguir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Compartilho 5 r\u00e1pidas dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal que com certeza est\u00e1 ai escondidinho.<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">#1 &#8211; Organize-se.<\/h3>\n\n\n\n<p><strong>Tenha visibilidade das suas prioridades pessoais e profissionais ao longo do ano<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">#2 &#8211; Seja Consistente.<\/h3>\n\n\n\n<p><strong>Mesmo quando n\u00e3o alcan\u00e7ar resultados imediatos, tenha e persiga a consist\u00eancia<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">#3 &#8211; Seja Respons\u00e1vel.<\/h3>\n\n\n\n<p><strong>Reconhe\u00e7a e compreenda que \u00e9 totalmente respons\u00e1vel por sua vida e pelas escolhas e decis\u00f5es que toma<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">#4 &#8211; Disciplina.<\/h3>\n\n\n\n<p><strong>Qualquer resultado pessoal ou profissional ser\u00e1 fruto da sua disciplina e dedica\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">#5 &#8211; Seja Flex\u00edvel.<\/h3>\n\n\n\n<p><strong>Adapte-se \u00e0s mudan\u00e7as rapidamente, mas sempre na dire\u00e7\u00e3o do seu principal objetivo.<\/strong><\/p>\n\n\n\n<p>Se voc\u00ea quer descobrir segredos para criar um ano novo com uma vida nova e planejamento de metas.<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Forma\u00e7\u00e3o de CEO (Chief Empaty Officer)<\/h2>\n\n\n\n<p>Inscreva-se na mentoria de <a href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/search-inside-yourself\/\">Intelig\u00eancia Emocional baseada em Mindfulness<\/a> para ser o novo l\u00edder que inspira confian\u00e7a, \u00e9 emp\u00e1tico e lidera com amorosidade. <a href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/search-inside-yourself\/\">Deixe seu nome em nossa lista de espera.<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Mentoria Intelig\u00eancia Emocional_Aten\u00e7\u00e3o Plena\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/7eC6ux5QH_I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Inscreva-se na mentoria de <a href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/search-inside-yourself\/\">Intelig\u00eancia Emocional baseada em Mindfulness<\/a> <\/figcaption><\/figure>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Protagonizar o papel de v\u00edtima, n\u00e3o saber onde quer chegar, n\u00e3o ter direcionamento, planejamento e viver sem perspectivas. Ser\u00e1 que pode realmente ser confort\u00e1vel viver sem lideran\u00e7a e poder pessoal? \u201cMinha meta \u00e9 n\u00e3o ter meta\u201d. Ouvi recentemente essa afirma\u00e7\u00e3o e, em um primeiro momento fiquei desconcertada, mas com alguma reflex\u00e3o lembrei-me de tr\u00eas longos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4168,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118,115],"tags":[],"class_list":["post-1837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-emocional","category-lideranca-humanizada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal<\/title>\n<meta name=\"description\" content=\"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal\" \/>\n<meta property=\"og:description\" content=\"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-04T11:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-18T20:56:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/05\/5-dicas-para-voce-resgatar-sua-lideranca-e-poder-pessoal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal\",\"datePublished\":\"2016-05-04T11:00:08+00:00\",\"dateModified\":\"2023-04-18T20:56:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\"},\"wordCount\":722,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Intelig\u00eancia emocional\",\"Lideran\u00e7a humanizada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\",\"name\":\"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-05-04T11:00:08+00:00\",\"dateModified\":\"2023-04-18T20:56:55+00:00\",\"description\":\"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal","description":"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/","og_locale":"pt_BR","og_type":"article","og_title":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal","og_description":"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.","og_url":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-05-04T11:00:08+00:00","article_modified_time":"2023-04-18T20:56:55+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/05\/5-dicas-para-voce-resgatar-sua-lideranca-e-poder-pessoal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/"},"author":{"name":"","@id":""},"headline":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal","datePublished":"2016-05-04T11:00:08+00:00","dateModified":"2023-04-18T20:56:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/"},"wordCount":722,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Intelig\u00eancia emocional","Lideran\u00e7a humanizada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/","url":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/","name":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-05-04T11:00:08+00:00","dateModified":"2023-04-18T20:56:55+00:00","description":"A mudan\u00e7a come\u00e7a com a coragem para escolher qual caminho voc\u00ea deseja seguir. Veja 5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/resgatar-sua-lideranca-e-seu-poder-pessoal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"5 dicas para voc\u00ea resgatar sua lideran\u00e7a e poder pessoal"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1837"}],"version-history":[{"count":7,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1837\/revisions"}],"predecessor-version":[{"id":5655,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1837\/revisions\/5655"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4168"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}