{"id":1846,"date":"2016-08-03T08:00:03","date_gmt":"2016-08-03T11:00:03","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=813"},"modified":"2023-03-22T11:55:29","modified_gmt":"2023-03-22T14:55:29","slug":"as-mentiras-que-nos-contam","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/","title":{"rendered":"As mentiras que nos contam e que a gente quase sempre acredita"},"content":{"rendered":"\n<p>Em algum momento da sua vida voc\u00ea acreditou ou ouviu que seria f\u00e1cil? Quantas vezes essas mentiras que nos contam n\u00e3o chegam aos nossos ouvidos:<\/p>\n\n\n\n<blockquote class=\"is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p><strong>&#8220;Ah, come\u00e7ar em um trabalho novo para mim foi f\u00e1cil\u201d<\/strong><\/p>\n\n\n<p><strong>&#8220;Empreender \u00e9 tranquilo, trabalho de casa e tenho flexibilidade&#8221;<\/strong><\/p>\n\n\n<p><strong>&#8220;Nossa, ganhar dinheiro no que eu fa\u00e7o \u00e9 moleza&#8221;<\/strong><\/p>\n\n<\/blockquote>\n\n\n\n<p>\u00c9 engra\u00e7ado ver como as pessoas se posicionam e adoram contar vantagens de que &#8220;o seu desafio&#8221; \u00e9 sempre mais f\u00e1cil do que o do outro. Isso entra na lista das mentiras que nos contam.<\/p>\n\n\n\n<p>E o pior de tudo: a gente acredita. Acreditamos porque nos conforta, nos gera sensa\u00e7\u00f5es boas, esperan\u00e7a e nos motiva a tentar cada vez mais.<\/p>\n\n\n\n<p>Mas eu tenho que dizer a verdade para voc\u00eas. N\u00e3o \u00e9 simples assim e nem t\u00e3o f\u00e1cil. Se voc\u00ea acha que chegou at\u00e9 aqui e est\u00e1 suficiente, a mensagem de hoje \u00e9 para voc\u00ea.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">As mentiras que nos contam: vida real<\/h2>\n\n\n\n<p>A realidade \u00e9 como ela \u00e9 e n\u00e3o como gostar\u00edamos que fosse. Gravei um v\u00eddeo para desmistificar algumas &#8220;verdades&#8221; que nos contam no mundo dos neg\u00f3cios, marketing, <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/descubra-como-reinventar-o-seu-business\/\" target=\"_blank\" rel=\"noreferrer noopener\">business com prop\u00f3sito<\/a>.<\/p>\n\n\n\n<p>What? Voc\u00ea acreditou?<\/p>\n\n\n\n<figure>\n<iframe title=\"WHAT? Voce\u0302 achou que seria fa\u0301cil?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/fPT6pxTuFDo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<p>Desafio: o que voc\u00ea gostaria de viver todos os dias? Conte para mim! Me conte o que voc\u00ea achou! Curta, compartilhe e envie para amigos! Quer ir al\u00e9m, quer se desafiar ainda mais no hoje e no agora?<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Medita\u00e7\u00e3o Gratuita<\/h2>\n\n\n\n<p>Para enfrentar este momento de mudan\u00e7a do mundo, o primeiro passo \u00e9 estar e viver no momento presente, com foco nos seus objetivos. <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/pratica-mindfulness-gratuita\" target=\"_blank\" rel=\"noreferrer noopener\">Baixe gratuitamente<\/a> a <strong>Medita\u00e7\u00e3o Mindfulness de Aten\u00e7\u00e3o Plena<\/strong> e treine seu foco hoje!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES \ud83d\ude42<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Em algum momento da sua vida voc\u00ea acreditou ou ouviu que seria f\u00e1cil? Quantas vezes essas mentiras que nos contam n\u00e3o chegam aos nossos ouvidos: &#8220;Ah, come\u00e7ar em um trabalho novo para mim foi f\u00e1cil\u201d &#8220;Empreender \u00e9 tranquilo, trabalho de casa e tenho flexibilidade&#8221; &#8220;Nossa, ganhar dinheiro no que eu fa\u00e7o \u00e9 moleza&#8221; \u00c9 engra\u00e7ado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4149,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114],"tags":[],"class_list":["post-1846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mentiras que nos contam e que a gente quase sempre acredita<\/title>\n<meta name=\"description\" content=\"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mentiras que nos contam e que a gente quase sempre acredita\" \/>\n<meta property=\"og:description\" content=\"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-03T11:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T14:55:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/08\/As-mentiras-que-nos-contam-e-que-a-gente-quase-sempre-acredita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"As mentiras que nos contam e que a gente quase sempre acredita\",\"datePublished\":\"2016-08-03T11:00:03+00:00\",\"dateModified\":\"2023-03-22T14:55:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\"},\"wordCount\":302,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\",\"name\":\"Mentiras que nos contam e que a gente quase sempre acredita\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-08-03T11:00:03+00:00\",\"dateModified\":\"2023-03-22T14:55:29+00:00\",\"description\":\"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As mentiras que nos contam e que a gente quase sempre acredita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mentiras que nos contam e que a gente quase sempre acredita","description":"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/","og_locale":"pt_BR","og_type":"article","og_title":"Mentiras que nos contam e que a gente quase sempre acredita","og_description":"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today","og_url":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-08-03T11:00:03+00:00","article_modified_time":"2023-03-22T14:55:29+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/08\/As-mentiras-que-nos-contam-e-que-a-gente-quase-sempre-acredita.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/"},"author":{"name":"","@id":""},"headline":"As mentiras que nos contam e que a gente quase sempre acredita","datePublished":"2016-08-03T11:00:03+00:00","dateModified":"2023-03-22T14:55:29+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/"},"wordCount":302,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/","url":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/","name":"Mentiras que nos contam e que a gente quase sempre acredita","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-08-03T11:00:03+00:00","dateModified":"2023-03-22T14:55:29+00:00","description":"\u00c9 engra\u00e7ado as mentiras que nos contam. Mudar n\u00e3o \u00e9 f\u00e1cil, mas o TGI Today pode te ajudar. Realize suas metas com o Guia de Metas do TGI Today","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/as-mentiras-que-nos-contam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"As mentiras que nos contam e que a gente quase sempre acredita"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":7,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1846\/revisions"}],"predecessor-version":[{"id":4927,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/1846\/revisions\/4927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4149"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}