{"id":2377,"date":"2018-06-26T21:33:03","date_gmt":"2018-06-27T00:33:03","guid":{"rendered":"https:\/\/tgitoday.com.br\/?p=2377"},"modified":"2023-03-21T12:24:05","modified_gmt":"2023-03-21T15:24:05","slug":"desafio-24-horas-nao-julgar","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/","title":{"rendered":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas?"},"content":{"rendered":"\n<p>Voc\u00ea j\u00e1 parou para pensar em quantas oportunidades voc\u00ea perdeu porque julgou algo ou algu\u00e9m no momento errado? Ou quantas pessoas \u00f3timas deixou de conhecer porque n\u00e3o soube n\u00e3o julgar quando deveria?<\/p>\n\n\n\n<p>Se a resposta foi sim, saiba que voc\u00ea n\u00e3o est\u00e1 sozinho. Todos n\u00f3s julgamos. Faz parte da natureza do nosso comportamento avaliar o mundo que est\u00e1 ao nosso redor. Mas tamb\u00e9m s\u00f3 depende de n\u00f3s mesmos evitar que isso afete a nossa vida de forma negativa.<\/p>\n\n\n\n<p><a style=\"color: #82b08c; text-decoration: underline;\" href=\"https:\/\/blog.ligiacostacom.br\/fora-do-mundo-corporativo\/\" target=\"_blank\" rel=\"noreferrer noopener\">No mundo corporativo<\/a>, esse tipo de julgamento se torna ainda mais comum, j\u00e1 que a apar\u00eancia e os resultados ganham ainda mais import\u00e2ncia. Por isso, depois que deixei de trabalhar nesse universo, uma das minhas metas foi rever alguns dos meus conceitos. E o &#8220;n\u00e3o julgar&#8221; come\u00e7ou a fazer parte do meu cotidiano.<\/p>\n\n\n\n<p>&#8220;Mas Ligia, como voc\u00ea faz isso? Como n\u00e3o julgar o tempo todo?&#8221;. N\u00e3o \u00e9 uma tarefa t\u00e3o simples. O mundo todo est\u00e1, a todo o momento, pedindo que julguemos, que avaliemos, que selecionemos o que acreditamos ser bom ou n\u00e3o para n\u00f3s.<\/p>\n\n\n\n<p>Por isso, deixar de lado o julgamento pode ser uma tarefa que demandar\u00e1 tempo. Mas eu garanto a voc\u00ea que ser\u00e1 recompensadora.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os benef\u00edcios de n\u00e3o julgar<\/h2>\n\n\n\n<p>Para ajudar voc\u00ea nessa empreitada, fiz um v\u00eddeo com um passo a passo super r\u00e1pido para voc\u00ea entrar no desafio agora e come\u00e7ar a julgar menos a partir de hoje! D\u00ea o play e n\u00e3o se esque\u00e7a de <a style=\"color: #82b08c; text-decoration: underline;\" href=\"http:\/\/bit.ly\/Inscrever-seYoutubeTGI\" target=\"_blank\" rel=\"noreferrer noopener\">se inscrever no nosso canal<\/a> para n\u00e3o perder nenhuma novidade!<\/p>\n\n\n\n<figure>\n<iframe title=\"DESAFIO 24 HORAS: voc\u00ea \u00e9 capaz de n\u00e3o julgar por um dia?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/8yaNc6a00V8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<p>Um dos principais benef\u00edcios de n\u00e3o julgar tanto a tudo e a todos \u00e9 que voc\u00ea se torna uma pessoa muito mais aberta a novas oportunidades e possibilidades. Outra grande vantagem de evitar o julgamento conscientemente \u00e9 a chance de treinarmos diariamente a nossa capacidade de nos colocarmos no lugar do outro.<\/p>\n\n\n\n<p>Frequentemente esquecemos que aquela pessoa, o alvo do nosso julgamento, \u00e9 um ser humano assim como n\u00f3s. Que tem medos, anseios e sonhos. E que pode ser negativamente afetado por esse nosso julgamento.<\/p>\n\n\n\n<p>Aprender a apreciar quem o outro realmente \u00e9, \u00e0 parte das apar\u00eancias e do que ele supostamente representa, \u00e9 um outro benef\u00edcio de n\u00e3o julgar que eu aprecio muito. Quando entendemos o outro como o ser humano que ele \u00e9, nos tornamos pessoas melhores por ver no outro o que ele tem de melhor!<\/p>\n\n\n\n<p>Voc\u00ea s\u00f3 ser\u00e1 capaz de <a style=\"color: #82b08c; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/empreendedorismo-com-proposito\/\" target=\"_blank\" rel=\"noreferrer noopener\">empreender com prop\u00f3sito<\/a> ou de liderar a pr\u00f3pria carreira a partir do momento que voc\u00ea tiver o foco em si pr\u00f3prio e n\u00e3o no outro!<\/p>\n\n\n\n<hr \/>\n\n\n\n<p>E a\u00ed? Voc\u00ea topa o meu desafio de ficar 24 horas sem julgar? Deixe um &#8220;Eu topo!&#8221; para mim nos coment\u00e1rios aqui embaixo e vamos juntos fazer um mundo mais emp\u00e1tico e menos julgador!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Minicurso Gratuito<\/h2>\n\n\n\n<p>Comece agora!&nbsp;<a style=\"color: #82b08c;\" href=\"https:\/\/www.ligiacosta.com.br\/minicurso-proposito-assistir\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Inscreva-se<\/strong><\/a><strong>&nbsp;no minicurso gratuito Prop\u00f3sito: 5 passos para ter um trabalho com significado.<\/strong>&nbsp;Nele voc\u00ea ter\u00e1 a oportunidade de iniciar o seu processo, um primeiro passo que poder\u00e1 gerar clareza e ao mesmo tempo curiosidade para um mundo de infinitas possibilidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES<\/h3>\n\n\n\n<h3 class=\"wp-block-heading\">Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea j\u00e1 parou para pensar em quantas oportunidades voc\u00ea perdeu porque julgou algo ou algu\u00e9m no momento errado? Ou quantas pessoas \u00f3timas deixou de conhecer porque n\u00e3o soube n\u00e3o julgar quando deveria? Se a resposta foi sim, saiba que voc\u00ea n\u00e3o est\u00e1 sozinho. Todos n\u00f3s julgamos. Faz parte da natureza do nosso comportamento avaliar o [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":3945,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[],"class_list":["post-2377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lideranca-humanizada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-27T00:33:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-21T15:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2018\/06\/Desafio-voce-e-capaz-de-nao-julgar-por-24-horas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas?\",\"datePublished\":\"2018-06-27T00:33:03+00:00\",\"dateModified\":\"2023-03-21T15:24:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\"},\"wordCount\":546,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Lideran\u00e7a humanizada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\",\"name\":\"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2018-06-27T00:33:03+00:00\",\"dateModified\":\"2023-03-21T15:24:05+00:00\",\"description\":\"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa","description":"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/","og_locale":"pt_BR","og_type":"article","og_title":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa","og_description":"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!","og_url":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/","og_site_name":"Blog Ligia Costa","article_published_time":"2018-06-27T00:33:03+00:00","article_modified_time":"2023-03-21T15:24:05+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2018\/06\/Desafio-voce-e-capaz-de-nao-julgar-por-24-horas.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/"},"author":{"name":"","@id":""},"headline":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas?","datePublished":"2018-06-27T00:33:03+00:00","dateModified":"2023-03-21T15:24:05+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/"},"wordCount":546,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Lideran\u00e7a humanizada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/","url":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/","name":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas? - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2018-06-27T00:33:03+00:00","dateModified":"2023-03-21T15:24:05+00:00","description":"Ser\u00e1 que voc\u00ea \u00e9 capaz de n\u00e3o julgar ningu\u00e9m durante um dia inteiro? Fa\u00e7a o desafio 24 horas do TGI Today e descubra se \u00e9 poss\u00edvel!","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/desafio-24-horas-nao-julgar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Desafio: voc\u00ea \u00e9 capaz de n\u00e3o julgar por 24 horas?"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/2377\/revisions"}],"predecessor-version":[{"id":4477,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/2377\/revisions\/4477"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/3945"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}