{"id":243,"date":"2016-01-11T08:00:09","date_gmt":"2016-01-11T10:00:09","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=243"},"modified":"2023-04-16T13:53:34","modified_gmt":"2023-04-16T16:53:34","slug":"criar-coragem","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/","title":{"rendered":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo"},"content":{"rendered":"\n<p>Palavras s\u00e1bias de um homeless na esta\u00e7\u00e3o rodovi\u00e1ria de San Francisco me mostraram que vale a pena batalhar e criar coragem de buscar seus&nbsp;<a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/sonhos-e-metas-de-sua-vida\/\">sonhos<\/a>.<\/p>\n\n\n\n<p>O primeiro emprego em minha carreira profissional foi em S\u00e3o Paulo, cidade onde nasci. Participei de um processo de sele\u00e7\u00e3o com diversos candidatos e felizmente conquistei um est\u00e1gio na \u00e1rea de Marketing de Produto na BraSoft. Era uma empresa brasileira importadora de softwares de entretenimento, l\u00edder no segmento de ind\u00fastria de games.<\/p>\n\n\n\n<p>Eu tinha apenas 19 anos, trabalhava o dia todo e a noite ia para a Universidade Mackenzie, onde cursava Publicidade com Especializa\u00e7\u00e3o em Marketing. Ap\u00f3s um ano de trabalho como estagi\u00e1ria, fui efetivada e passei a ter mais responsabilidades e acesso a novas informa\u00e7\u00f5es e conhecimentos e <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/o-brasil-na-contramao-da-inovacao\/\">inova\u00e7\u00e3o<\/a>.<\/p>\n\n\n\n<p>Com o tempo, assumi novos projetos e tive a oportunidade de ter contato com as grandes multinacionais produtoras de games no mundo. Sempre fui muito curiosa e determinada e naquele momento percebi que seria a hora de realizar um grande sonho: criar coragem para fazer o meu primeiro est\u00e1gio no exterior.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Coragem para ser quem voc\u00ea \u00e9\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/3uSUkH_XmP4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Pare por alguns minutos e se conecte com o seu momento presente para ser quem voc\u00ea j\u00e1 \u00e9.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Em busca do sim<\/h2>\n\n\n\n<p>Um belo dia, mesmo com muito <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superar-o-medo-do-fracasso\/\" target=\"_blank\" rel=\"noreferrer noopener\">medo<\/a>, mas com toda coragem e a maior cara-de-pau do mundo, bati na porta do presidente da empresa. Surpreso, ele me pediu para entrar. Sentei a sua frente, determinada a criar coragem, e em menos de cinco minutos eu o havia convencido de que seria muito importante para minha carreira ter uma experi\u00eancia internacional.<\/p>\n\n\n\n<p>Eu gostaria de aprender mais, estudar e obter novos conhecimentos. Fui muito honesta quando disse que meu objetivo era morar e trabalhar no exterior e, para que o plano se concretizasse, eu precisaria da sua ajuda. Foi incr\u00edvel quando ele olhou para mim e falou:<\/p>\n\n\n\n<blockquote class=\"is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p>\u201cL\u00f3gico, Ligia. Parab\u00e9ns pela sua atitude. Eu vou ajudar voc\u00ea a realizar o seu sonho. S\u00f3 tem um por\u00e9m. N\u00e3o vou poder arcar com seus custos\u201d.<\/p>\n\n<\/blockquote>\n\n\n\n<p>A partir daquele dia, eu s\u00f3 sonhava com aquela experi\u00eancia e em menos de duas semanas chegou a autoriza\u00e7\u00e3o da Lucas Entertaiment Arts &#8211; simplesmente a produtora de games do George Lucas &#8211; com o convite em meu nome, oficializando o est\u00e1gio por tr\u00eas meses na \u00e1rea de Marketing da empresa.<\/p>\n\n\n\n<p>Parte do sonho estava realizado, eu s\u00f3 precisava criar coragem e me programar financeiramente para embarcar em minha primeira aventura no Vale do Sil\u00edcio.&nbsp;Rapidamente montei um planejamento de viagem, levantei todas minhas economias, comprei passagens a\u00e9reas, aluguei resid\u00eancia corporativa e embarquei, ent\u00e3o, para San Rafael, Vale do Sil\u00edcio, Calif\u00f3rnia, onde seria minha primeira aventura profissional no exterior para uma vida e profiss\u00e3o com mais <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/hoje-e-o-dia-ideal-para-voce-comecar-viver-com-mais-significado\/\">significado<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Criar coragem para a temporada americana<\/h2>\n\n\n\n<p>N\u00e3o foi nada f\u00e1cil. Tive dificuldade com a l\u00edngua, o estilo de trabalho dos americanos, o ritmo de vida, a solid\u00e3o, o frio, o fuso hor\u00e1rio. N\u00e3o existiam redes sociais. Estamos falando de 1998, 1999 (eu tinha 19 anos, hoje tenho 38).<\/p>\n\n\n\n<p>Eu s\u00f3 podia ligar para minha fam\u00edlia quando estava em casa e as seis horas de fuso dificultavam a comunica\u00e7\u00e3o. Eu n\u00e3o tinha carro, porque a idade m\u00ednima para dirigir nos Estados Unidos era 21 anos. Dependia de transporte p\u00fablico e carona.<\/p>\n\n\n\n<p>Caminhava mais de 20 minutos at\u00e9 o topo de uma montanha para chegar at\u00e9 a minha resid\u00eancia no Highlands of Marin. Os finais de semana eram longos, eu estava longe dos grandes centros, n\u00e3o tinha muito onde passear.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O privil\u00e9gio da experi\u00eancia<\/h2>\n\n\n\n<p>Mas, ao mesmo tempo, tive experi\u00eancias incr\u00edveis, mostrando que valeu a pena criar coragem e mergulhar nesse projeto. Meu projeto de est\u00e1gio foi na \u00e1rea de internet e naquele tempo eu n\u00e3o sabia muito o que isso significava. Tive a oportunidade de visitar os est\u00fadios do George Lucas, inclusive almocei ao seu lado.<\/p>\n\n\n\n<p>Pude vivenciar como funcion\u00e1ria o relan\u00e7amento da Trilogia Star Wars, assisti ao pr\u00e9-lan\u00e7amento e fui ao churrasco de comemora\u00e7\u00e3o do sucesso atingido. Tirei fotos com Darth Vader, aprendi como se cria desenhos, as etapas de layout, cria\u00e7\u00e3o, anima\u00e7\u00e3o. Participei de reuni\u00f5es com ag\u00eancias de publicidade, apresenta\u00e7\u00f5es de campanhas de lan\u00e7amento de desenhos, enfim, sou muito privilegiada de ter tido esta oportunidade.<\/p>\n\n\n\n<p>No final do meu est\u00e1gio, para minha alegria, todos da equipe de Marketing escreveram mensagens e foram muito simp\u00e1ticos, o que me emocionou, pois realmente me senti vitoriosa, sabe aquela<a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/atitudes-de-campeao\/\"> atitude de campe\u00e3<\/a>, em ter conclu\u00eddo aquele projeto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hora de retornar<\/h2>\n\n\n\n<p>Havia, ent\u00e3o, chegado a hora de retornar ao Brasil. Estava na esta\u00e7\u00e3o em San Rafael, onde pegaria o \u00f4nibus que me levaria a San Francisco e em seguida eu iria ao aeroporto.<\/p>\n\n\n\n<p>Sentimentos contradit\u00f3rios me acompanharam durante todo o per\u00edodo em que estive por l\u00e1. Estava muito feliz e ao mesmo tempo apreensiva e muito sozinha. A esta\u00e7\u00e3o de \u00f4nibus era vazia, n\u00e3o tinha ningu\u00e9m, o que me deixava muito tensa.<\/p>\n\n\n\n<p>De repente um mendigo maltrapilho come\u00e7ou a caminhar em minha dire\u00e7\u00e3o e eu ao mesmo tempo comecei a ficar em p\u00e2nico. Ele chegou bem perto, olhou para mim e disse: You are so beautiful!<\/p>\n\n\n\n<p>Quando olhei novamente, talvez minha cara de espanto tenha o assustado e ele seguiu em outra dire\u00e7\u00e3o. Eu ainda permaneci mais alguns minutos no local at\u00e9 que o \u00f4nibus chegou. Embarquei e, com a sensa\u00e7\u00e3o de al\u00edvio e a lembran\u00e7a da frase daquele mendigo, cai no choro&#8230;<\/p>\n\n\n\n<p>A minha miss\u00e3o havia sido cumprida e eu havia conquistado mais uma etapa, realizado um sonho. A palavra \u201cbeautiful\u201d (bonita) naquele momento teve milhares de significados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Todo dia \u00e9 dia para criar coragem de dar o primeiro passo<\/h2>\n\n\n\n<p><strong>Dica #1 &#8211; &nbsp;Batalhe pelos seus sonhos. Ningu\u00e9m far\u00e1 por voc\u00ea.<\/strong><\/p>\n\n\n\n<p><strong>Dica #2 &#8211; Quanto maior o desafio superado, maior a satisfa\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p><strong>Dica #3 &#8211; O \u201cN\u00e3o\u201d voc\u00ea j\u00e1 tem como resposta. Tente o \u201cSim\u201d.<\/strong><\/p>\n\n\n\n<p><strong>Dica #4 &#8211; Fa\u00e7o do mendigo as minhas palavras para voc\u00ea: YOU ARE BEAUTIFUL!<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"A coragem de se reinventar\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/jovCo-reouc?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Assista e inspire-se em cases reais de pessoas que escolhem a coragem de se reinventar.<\/figcaption><\/figure>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Webin\u00e1rio Gratuito<\/h2>\n\n\n\n<p>Inscreva-se no <strong>webin\u00e1rio Equil\u00edbrio Vida &amp; Trabalho <\/strong><a style=\"color: #82a892;\" href=\"https:\/\/www.ligiacosta.com.br\/webinario-4-passos-equilibrio\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>clicando aqui<\/strong><\/a> e Descubra os 4 passos para voc\u00ea equilibrar a sua vida pessoal e profissional, criar metas e focar no que \u00e9 importante. S\u00f3 assim voc\u00ea ter\u00e1 alta performance.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Webinar Equil\u00edbrio Alta Performance\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/uNpPyUeqGAs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Assista ao<a href=\"https:\/\/ligiacosta.com.br\/webinario-4-passos-equilibrio\/\"> Webinar clicando aqui<\/a> e em seguida inscreva-se no curso 100% Online Alta Performance.<\/figcaption><\/figure>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES \ud83d\ude42<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Palavras s\u00e1bias de um homeless na esta\u00e7\u00e3o rodovi\u00e1ria de San Francisco me mostraram que vale a pena batalhar e criar coragem de buscar seus&nbsp;sonhos. O primeiro emprego em minha carreira profissional foi em S\u00e3o Paulo, cidade onde nasci. Participei de um processo de sele\u00e7\u00e3o com diversos candidatos e felizmente conquistei um est\u00e1gio na \u00e1rea de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4245,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[114,116],"tags":[],"class_list":["post-243","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categ-empreendedorismo-com-proposito","category-transicao-de-carreira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo<\/title>\n<meta name=\"description\" content=\"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo\" \/>\n<meta property=\"og:description\" content=\"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-11T10:00:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-16T16:53:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/4-dicas-para-voce-criar-coragem-e-fazer-o-que-quiser-sem-medo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo\",\"datePublished\":\"2016-01-11T10:00:09+00:00\",\"dateModified\":\"2023-04-16T16:53:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\"},\"wordCount\":1172,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Empreendedorismo com prop\u00f3sito\",\"Transi\u00e7\u00e3o de carreira\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\",\"name\":\"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-01-11T10:00:09+00:00\",\"dateModified\":\"2023-04-16T16:53:34+00:00\",\"description\":\"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo","description":"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/","og_locale":"pt_BR","og_type":"article","og_title":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo","og_description":"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional","og_url":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-01-11T10:00:09+00:00","article_modified_time":"2023-04-16T16:53:34+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/01\/4-dicas-para-voce-criar-coragem-e-fazer-o-que-quiser-sem-medo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/"},"author":{"name":"","@id":""},"headline":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo","datePublished":"2016-01-11T10:00:09+00:00","dateModified":"2023-04-16T16:53:34+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/"},"wordCount":1172,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Empreendedorismo com prop\u00f3sito","Transi\u00e7\u00e3o de carreira"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/","url":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/","name":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-01-11T10:00:09+00:00","dateModified":"2023-04-16T16:53:34+00:00","description":"Saiba o que aprendi sobre criar coragem quando decidi que queria fazer um est\u00e1gio internacional e como essa li\u00e7\u00e3o mudou minha carreira profissional","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/criar-coragem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"4 dicas para voc\u00ea criar coragem e fazer o que quiser sem medo"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=243"}],"version-history":[{"count":7,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/243\/revisions"}],"predecessor-version":[{"id":5578,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/243\/revisions\/5578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4245"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}