{"id":261,"date":"2016-02-04T08:00:04","date_gmt":"2016-02-04T10:00:04","guid":{"rendered":"http:\/\/ligiacosta.com\/?p=261"},"modified":"2023-03-22T13:54:43","modified_gmt":"2023-03-22T16:54:43","slug":"aprender-com-os-erros","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/","title":{"rendered":"Aprender com os erros e seguir firme em outras empreitadas"},"content":{"rendered":"\n<p>Qual o risco do seu projeto dar errado? Qual o risco de voc\u00ea ser demitido? Qual o risco daquele trabalho n\u00e3o sair exatamente do jeito que voc\u00ea idealizou? Enorme, gigante, grande. Por isso que \u00e9 importante que voc\u00ea saiba aprender com os erros.<\/p>\n\n\n\n<p>Realmente, existe risco em tudo que fazemos. E o pior \u00e9 que existe o risco de falharmos e de repente tudo ir por \u00e1gua abaixo mais r\u00e1pido do que imagin\u00e1vamos. Pior ainda, \u00e9 poss\u00edvel que o \u201cdar tudo errado\u201d possa acontecer v\u00e1rias vezes em sua vida.<\/p>\n\n\n\n<p>Voc\u00ea sabia que quase metade das empresas fecha em tr\u00eas anos? De cada 100 empresas brasileiras, 48 fecham ap\u00f3s tr\u00eas anos de atividade, segundo o IBGE.&nbsp;O principal motivo \u00e9 a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/erros-estrategia-planejamento-empreendedorismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">falta de planejamento<\/a> e conhecimento do mercado de atua\u00e7\u00e3o. As pessoas simplesmente agem, falham e se deprimem. Por isso aprender com os erros \u00e9 fundamental para ser bem sucedido<\/p>\n\n\n\n<p>Muito provavelmente voc\u00ea j\u00e1 come\u00e7ou projetos uma, duas, v\u00e1rias, muitas vezes na sua vida e parou. Eu sei que voc\u00ea luta contra isso.&nbsp;A gente morre de medo de falhar. \u00c9 mais comum desistirmos a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superar-o-medo-do-fracasso\/\" target=\"_blank\" rel=\"noreferrer noopener\">enfrentar o medo<\/a> de falhar. Mas melhor tentar, falhar e aprender com o erros do que arrepender-se de nunca t\u00ea-lo feito.<\/p>\n\n\n\n<blockquote class=\"is-layout-flow wp-block-quote-is-layout-flow\">\n\n<p>A diferen\u00e7a entre um homem de sucesso e outro orientado pelo fracasso \u00e9 que um est\u00e1 aprendendo a errar, enquanto que o outro est\u00e1 procurando aprender com os erros que cometeu&#8221; \u2014 <em>Conf\u00facio (pensador e fil\u00f3sofo chin\u00eas)<\/em><\/p>\n\n<\/blockquote>\n\n\n\n<p>E, para que voc\u00ea possa aprender com os erros, o primeiro passo \u00e9 trabalharmos nossas expectativas e o nosso n\u00edvel de exig\u00eancia, como uma tentativa de que nossa pr\u00f3pria cobran\u00e7a n\u00e3o nos bloqueie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">A&nbsp;partir de hoje utilizaremos um novo modelo mental para aprender com os erros<\/h2>\n\n\n\n<p>Redirecionaremos o nosso n\u00edvel de exig\u00eancia, transformando-o em prefer\u00eancia.<\/p>\n\n\n\n<p>E vamos \u00e0 pr\u00e1tica. A partir de hoje &#8211; afinal hoje \u00e9 e ser\u00e1 sempre o grande dia &#8211; ao inv\u00e9s de dizer: Isto tem que dar certo, tem que ser perfeito, tem que ser do jeito que planejei; vamos passar a pensar: Eu prefiro que d\u00ea certo, eu prefiro que seja perfeito, eu prefiro que seja do jeito que planejei.<\/p>\n\n\n\n<p>E, se tudo der errado? N\u00e3o se preocupe, isto n\u00e3o \u00e9 o fim do mundo. Voc\u00ea sempre pode aprender com seus erros. Ningu\u00e9m morre com isso e, definitivamente, n\u00e3o \u00e9 uma trag\u00e9dia. \u00c9 apenas um inconveniente. Acredite nisto, ajudar\u00e1 voc\u00ea a <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/continuar-ou-desistir-o-final-da-sua-historia-quem-decide-e-voce\/\" target=\"_blank\" rel=\"noreferrer noopener\">superar mais rapidamente<\/a>.<\/p>\n\n\n\n<p>Se necess\u00e1rio, mentalize e repita v\u00e1rias vezes: A realidade \u00e9 como ela \u00e9 e n\u00e3o como eu gostaria que fosse. O universo n\u00e3o foi constru\u00eddo para que eu, de todas as outras pessoas, tenha uma vida mais f\u00e1cil do que os outros.&nbsp;Aos poucos, voc\u00ea resgatar\u00e1 a confian\u00e7a de seguir adiante.<\/p>\n\n\n\n<p><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/business-academy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Recomece com foco, planejamento e prop\u00f3sito<\/a>. Tenho certeza de que, quanto mais praticar seu trabalho de intelig\u00eancia emocional, mais voc\u00ea estar\u00e1 fortalecido para a pr\u00f3xima empreitada!<\/p>\n\n\n\n<hr \/>\n\n\n\n<h3 class=\"wp-block-heading\">Leia mais<\/h3>\n\n\n\n<p><strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/continuar-ou-desistir-o-final-da-sua-historia-quem-decide-e-voce\/\" target=\"_blank\" rel=\"noreferrer noopener\">Continuar ou desistir: o final da sua hist\u00f3ria quem decide \u00e9 voc\u00ea<\/a><\/strong><\/p>\n<p>\n\n\n\n<\/p>\n<p><strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/superar-o-medo-do-fracasso\/\" target=\"_blank\" rel=\"noreferrer noopener\">5 dicas para voc\u00ea superar o medo do fracasso a partir de hoje<\/a><\/strong><\/p>\n<p>\n\n\n\n<\/p>\n<p><strong><a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/erros-estrategia-planejamento-empreendedorismo\/\" target=\"_blank\" rel=\"noreferrer noopener\">10 erros b\u00e1sicos de estrat\u00e9gia e planejamento que empreendedores cometem<\/a><\/strong><\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Para a Sandra, esse recome\u00e7o veio com a ajuda do <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/business-academy\/\" target=\"_blank\" rel=\"noreferrer noopener\">Business Academy<\/a>, o programa de 8 semanas do TGI Today que a ajudou a ter mais clareza e foco do que queria fazer, dando as ferramentas necess\u00e1rias para isso! Assista ao v\u00eddeo e conhe\u00e7a mais sobre a hist\u00f3ria dela!<\/p>\n\n\n\n<figure>\n<iframe title=\"O Dia que a Chave Virou - Sandra Miguel\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/Srv6tIc6lyY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<hr \/>\n\n\n\n<h2 class=\"wp-block-heading\">Medita\u00e7\u00e3o Gratuita<\/h2>\n\n\n\n<p>Para enfrentar este momento de mudan\u00e7a do mundo, o primeiro passo \u00e9 estar e viver no momento presente, com foco nos seus objetivos. <a style=\"color: #82a892; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/pratica-mindfulness-gratuita\" target=\"_blank\" rel=\"noreferrer noopener\">Baixe gratuitamente<\/a> a <strong>Medita\u00e7\u00e3o Mindfulness de Aten\u00e7\u00e3o Plena<\/strong> e treine seu foco hoje!<\/p>\n\n\n\n<hr \/>\n\n\n\n<p>Gostou? Ent\u00e3o comente, compartilhe e ative as notifica\u00e7\u00f5es clicando no sininho ali no canto para receber novos textos em primeira m\u00e3o no seu e-mail.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">HUGS &amp; KISSES <br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Qual o risco do seu projeto dar errado? Qual o risco de voc\u00ea ser demitido? Qual o risco daquele trabalho n\u00e3o sair exatamente do jeito que voc\u00ea idealizou? Enorme, gigante, grande. Por isso que \u00e9 importante que voc\u00ea saiba aprender com os erros. Realmente, existe risco em tudo que fazemos. E o pior \u00e9 que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":4230,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[117],"tags":[],"class_list":["post-261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gente-que-inspira"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-04T10:00:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-22T16:54:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/02\/Aprender-com-os-erros-e-seguir-firme-em-outras-empreitadas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Aprender com os erros e seguir firme em outras empreitadas\",\"datePublished\":\"2016-02-04T10:00:04+00:00\",\"dateModified\":\"2023-03-22T16:54:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\"},\"wordCount\":689,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Gente que inspira\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\",\"name\":\"Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2016-02-04T10:00:04+00:00\",\"dateModified\":\"2023-03-22T16:54:43+00:00\",\"description\":\"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aprender com os erros e seguir firme em outras empreitadas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa","description":"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/","og_locale":"pt_BR","og_type":"article","og_title":"Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa","og_description":"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.","og_url":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/","og_site_name":"Blog Ligia Costa","article_published_time":"2016-02-04T10:00:04+00:00","article_modified_time":"2023-03-22T16:54:43+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2016\/02\/Aprender-com-os-erros-e-seguir-firme-em-outras-empreitadas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/"},"author":{"name":"","@id":""},"headline":"Aprender com os erros e seguir firme em outras empreitadas","datePublished":"2016-02-04T10:00:04+00:00","dateModified":"2023-03-22T16:54:43+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/"},"wordCount":689,"commentCount":0,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Gente que inspira"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/","url":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/","name":"Aprender com os erros e seguir firme em outras empreitadas - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2016-02-04T10:00:04+00:00","dateModified":"2023-03-22T16:54:43+00:00","description":"\u00c9 mais comum desistirmos a enfrentar o medo de falhar. Mas como aprender com os erros? O segredo \u00e9 resgatar a confian\u00e7a e seguir firme.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/aprender-com-os-erros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Aprender com os erros e seguir firme em outras empreitadas"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=261"}],"version-history":[{"count":6,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/261\/revisions"}],"predecessor-version":[{"id":5136,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/261\/revisions\/5136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/4230"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}