{"id":3539,"date":"2020-06-01T07:00:00","date_gmt":"2020-06-01T10:00:00","guid":{"rendered":"https:\/\/blog.tgitoday.com.br\/?p=3539"},"modified":"2023-03-20T18:00:13","modified_gmt":"2023-03-20T21:00:13","slug":"o-que-e-meditacao","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/","title":{"rendered":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar"},"content":{"rendered":"\n<p>Desde que comecei meu trabalho como instrutora de medita\u00e7\u00e3o mindfulness, um dos questionamentos que mais recebo \u00e9 justamente o que \u00e9 medita\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por isso, vou te trazer aqui algumas dicas super simples para entender melhor e come\u00e7ar a praticar hoje.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">O que \u00e9 medita\u00e7\u00e3o?<\/h2>\n\n\n\n<p>Medita\u00e7\u00e3o nada mais \u00e9 do que um treino mental. Mas por que que hoje em dia t\u00e1 t\u00e3o em evid\u00eancia? Isso \u00e9 importante voc\u00ea saber.<\/p>\n\n\n\n<p>Desde 2010, alguns cientistas come\u00e7aram a comprovar a efici\u00eancia dessa pr\u00e1tica. Esse treino mental traz para gente mais foco, regula\u00e7\u00e3o emocional e bem-estar.<\/p>\n\n\n\n<p>Para entender o que \u00e9 medita\u00e7\u00e3o, a gente precisa compreender que pode, sim, treinar a nossa mente para ser mais feliz, para trazer a nossa aten\u00e7\u00e3o para o nosso momento presente.<\/p>\n\n\n\n<p>Quando a gente fala de regula\u00e7\u00e3o emocional, para reduzir o nosso estresse, a nossa ansiedade, tudo isso \u00e9 comprovado hoje em dia pela ci\u00eancia.<\/p>\n\n\n\n<p>Voc\u00ea pode ver mais dicas no meu v\u00eddeo dando play aqui embaixo!<\/p>\n\n\n\n<figure>\n<iframe title=\"O que \u00e9 medita\u00e7\u00e3o mindfulness e como praticar\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/jSThFiK7sjQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Como come\u00e7ar a meditar?<\/h2>\n\n\n\n<p>Ent\u00e3o como voc\u00ea pode fazer entender o que \u00e9 medita\u00e7\u00e3o e <a style=\"color: #81b89b; text-decoration: underline;\" href=\"https:\/\/ligiacosta.com.br\/blog\/como-comecar-a-meditar\/\" target=\"_blank\" rel=\"noreferrer noopener\">come\u00e7ar a praticar a partir de hoje? <\/a>Voc\u00ea pode primeiro procurar um aplicativo gratuito, tem v\u00e1rios dispon\u00edveis.<\/p>\n\n\n\n<p>Existem tamb\u00e9m v\u00e1rios livros que voc\u00ea pode ler sobre medita\u00e7\u00e3o para se informar mais.<\/p>\n\n\n\n<p><a style=\"color: #81b89b; text-decoration: underline;\" href=\"https:\/\/sptfy.com\/9b5f~s\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"No meu Spotify (opens in a new tab)\">No meu Spotify<\/a> eu tamb\u00e9m disponibilizo pr\u00e1ticas, voc\u00ea pode ir l\u00e1 buscar pelas pr\u00e1ticas gratuitas.<\/p>\n\n\n\n<p>Voc\u00ea pode fazer treinamentos de medita\u00e7\u00e3o mindfulness. Eu tenho uma <a style=\"color: #81b89b; text-decoration: underline;\" href=\"https:\/\/www.sympla.com.br\/ligiacosta\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"agenda de treinamentos online  (opens in a new tab)\">agenda de treinamentos online <\/a>porque da\u00ed a gente aprende de forma estruturada.<\/p>\n\n\n\n<p>As pr\u00e1ticas de medita\u00e7\u00e3o v\u00e3o contribuir para a nossa <a href=\"https:\/\/ligiacosta.com.br\/blog\/autocompaixao\/\" target=\"_blank\" rel=\"noreferrer noopener\">intelig\u00eancia emocional<\/a>, para que a gente possa n\u00e3o s\u00f3 viver no momento presente, estar autoconsciente, mas tamb\u00e9m atuar e nos comunicar com todos os outros.<\/p>\n\n\n\n<p>Meditar nos permite interagir de uma forma plena, com conex\u00e3o, com empatia, gerando confian\u00e7a, que \u00e9 o que a gente realmente deseja.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dicas para iniciantes<\/h3>\n\n\n\n<p>A medita\u00e7\u00e3o \u00e9 simples, mas voc\u00ea precisa de algumas t\u00e9cnicas. Vamos l\u00e1, se voc\u00ea quer come\u00e7ar a meditar a partir de hoje, primeiro, arrume um tempo.<\/p>\n\n\n\n<p>Pode ser um minuto. N\u00e3o tou te falando para arrumar 20, 30 minutos, n\u00e3o. Arrume um minutinho. Tenha a sua inten\u00e7\u00e3o e comece a participar de alguns grupos.<\/p>\n\n\n\n<p>No meu canal do YouTube eu disponibilizo uma pr\u00e1tica nova quarta-feira, voc\u00ea pode ir l\u00e1 e aproveitar essa medita\u00e7\u00e3o guiada.<\/p>\n\n\n\n<figure>\n<iframe title=\"Medita\u00e7\u00e3o mindfulness para iniciantes\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PL7CIB_HFDdJi8rZ6Rt2FqBZM3PFQ-sRdM\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/figure>\n\n\n\n<p>Para algumas pessoas faz mais sentido voc\u00ea seguir uma voz, algu\u00e9m que est\u00e1 orientando.<\/p>\n\n\n\n<p>Para outras, o sil\u00eancio tamb\u00e9m pode ser uma forma de medita\u00e7\u00e3o. Voc\u00ea pode caminhar e simplesmente prestar aten\u00e7\u00e3o em todo seu redor, sem m\u00fasica, sem conversa, simplesmente estando ali no seu momento presente.<\/p>\n\n\n\n<p>Isso tamb\u00e9m pode ser uma forma de medita\u00e7\u00e3o. Voc\u00ea pode tamb\u00e9m passar a viver o seu dia inteiro com a presen\u00e7a, estando mindful, vivenciando todos os momentos do seu dia com aten\u00e7\u00e3o plena.<\/p>\n\n\n\n<p>Medita\u00e7\u00e3o \u00e9 um treino mental, quanto mais voc\u00ea pratica, mais voc\u00ea vai condicionando a sua mente para este treino.<\/p>\n\n\n\n<p>\u00c9 como se voc\u00ea fosse numa academia, a gente fala que \u00e9 exatamente a mesma coisa. S\u00f3 que esse treino mental, ele est\u00e1 trabalhando o c\u00f3rtex pr\u00e9-frontal.<\/p>\n\n\n\n<p>\u00c9 uma parte executiva do nosso c\u00e9rebro, respons\u00e1vel pelo discernimento, pelo controle das emo\u00e7\u00f5es, pelo foco.<\/p>\n\n\n\n<p>Quanto mais voc\u00ea pratica, mais voc\u00ea fortalece essa \u00e1rea do seu c\u00e9rebro, que vai te ajudar a ter mais foco, a regular as suas emo\u00e7\u00f5es e a viver com mais bem-estar.<\/p>\n\n\n\n<hr \/>\n\n\n\n<p><strong>Desenvolva sua aten\u00e7\u00e3o plena hoje! Clique aqui e&nbsp;<\/strong><a href=\"https:\/\/ligiacosta.com.br\/pratica-atencao-plena-opt-in\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>baixe gratuitamente<\/strong><\/a><strong>&nbsp;nossa pr\u00e1tica de aten\u00e7\u00e3o plena.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hugs &amp; Kisses<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Desde que comecei meu trabalho como instrutora de medita\u00e7\u00e3o mindfulness, um dos questionamentos que mais recebo \u00e9 justamente o que \u00e9 medita\u00e7\u00e3o. Por isso, vou te trazer aqui algumas dicas super simples para entender melhor e come\u00e7ar a praticar hoje. O que \u00e9 medita\u00e7\u00e3o? Medita\u00e7\u00e3o nada mais \u00e9 do que um treino mental. Mas por [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":3891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[118],"tags":[],"class_list":["post-3539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inteligencia-emocional"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-01T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-20T21:00:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2020\/06\/O-que-e-meditacao-e-como-comecar-a-praticar.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar\",\"datePublished\":\"2020-06-01T10:00:00+00:00\",\"dateModified\":\"2023-03-20T21:00:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\"},\"wordCount\":650,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Intelig\u00eancia emocional\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\",\"name\":\"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2020-06-01T10:00:00+00:00\",\"dateModified\":\"2023-03-20T21:00:13+00:00\",\"description\":\"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa","description":"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/","og_locale":"pt_BR","og_type":"article","og_title":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa","og_description":"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!","og_url":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/","og_site_name":"Blog Ligia Costa","article_published_time":"2020-06-01T10:00:00+00:00","article_modified_time":"2023-03-20T21:00:13+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2020\/06\/O-que-e-meditacao-e-como-comecar-a-praticar.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/"},"author":{"name":"","@id":""},"headline":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar","datePublished":"2020-06-01T10:00:00+00:00","dateModified":"2023-03-20T21:00:13+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/"},"wordCount":650,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Intelig\u00eancia emocional"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/","url":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/","name":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2020-06-01T10:00:00+00:00","dateModified":"2023-03-20T21:00:13+00:00","description":"Entenda melhor o que \u00e9 medita\u00e7\u00e3o e como voc\u00ea pode come\u00e7ar a praticar a partir de agora com algumas dicas pr\u00e1ticas e simples!","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/o-que-e-meditacao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"O que \u00e9 medita\u00e7\u00e3o e como come\u00e7ar a praticar"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3539"}],"version-history":[{"count":9,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3539\/revisions"}],"predecessor-version":[{"id":4347,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3539\/revisions\/4347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/3891"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}