{"id":3795,"date":"2021-10-07T23:02:04","date_gmt":"2021-10-08T02:02:04","guid":{"rendered":"https:\/\/blog.tgitoday.com.br\/?p=3795"},"modified":"2023-04-27T12:13:03","modified_gmt":"2023-04-27T15:13:03","slug":"futuro-da-lideranca","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/","title":{"rendered":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a"},"content":{"rendered":"\n<p><strong>Ligia Costa<\/strong><\/p>\n\n\n\n<p>Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar.&nbsp; Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o e falta de significado. N\u00e3o ter\u00e1 futuro a empresa que n\u00e3o considerar esses pontos, que n\u00e3o pensar na sa\u00fade mental de seus funcion\u00e1rios e na import\u00e2ncia de todos trabalharem motivados, encontrando sentido naquilo que fazem. N\u00e3o \u00e9 mais uma quest\u00e3o de chegar, bater o ponto e simplesmente ver o tempo passar fazendo o b\u00e1sico, o suficiente, at\u00e9 a hora de voltar para casa.<\/p>\n\n\n\n<p>Na minha avalia\u00e7\u00e3o, tudo isso passa por uma crise profunda na lideran\u00e7a, de modo que as rela\u00e7\u00f5es nas equipes est\u00e3o insustent\u00e1veis. Para se ter uma ideia de como a situa\u00e7\u00e3o \u00e9 grave, segundo informa\u00e7\u00f5es da Secretaria Especial da Previd\u00eancia e Trabalho, mais de 576 mil brasileiros foram afastados do emprego em 2020 por conta de transtornos mentais e de comportamento. Trata-se de um crescimento de 26% em rela\u00e7\u00e3o ao registrado em 2019.<\/p>\n\n\n\n<p>Em outras palavras, n\u00e3o haver\u00e1 empenho, produtividade e inova\u00e7\u00e3o se as organiza\u00e7\u00f5es n\u00e3o forem capazes de acolher e incentivar seus colaboradores. Se os l\u00edderes n\u00e3o tiverem a empatia e a compaix\u00e3o como bases da condu\u00e7\u00e3o de seus times. N\u00e3o \u00e9 mais sobre mim, os meus feitos e reconhecimento individual, mas sim sobre n\u00f3s, as conquistas coletivas e a colabora\u00e7\u00e3o.<\/p>\n\n\n\n<p>F\u00e1cil, n\u00e3o, por\u00e9m estamos todos precisando de um respiro de gentileza para seguirmos fortes nesse processo de transforma\u00e7\u00e3o, os l\u00edderes precisam assumir o seu papel nesse contexto.<\/p>\n\n\n\n<p>A l\u00f3gica por tr\u00e1s disso tudo est\u00e1 no fato de que a <strong>motiva\u00e7\u00e3o que emerge da autocompaix\u00e3o vem do amor, enquanto os est\u00edmulos que surgem da autocr\u00edtica s\u00e3o decorrentes do medo.<\/strong> Liderar amorosamente tem mais poder de conquistar cora\u00e7\u00f5es e mentes do que promovendo conflitos e disputas. \u00c9 assim que os colaboradores v\u00e3o conseguir trabalhar melhor, ver sentido naquilo que fazem durante o expediente.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Autocompaix\u00e3o: como ter mais empatia com voc\u00ea\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/EAjC1hU5lgA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><figcaption class=\"wp-element-caption\">Autocompaix\u00e3o, como ter mais empatia com voc\u00ea.<\/figcaption><\/figure>\n\n\n\n<p>Um mundo no qual a busca pelo poder e pelo status individual precisa dar espa\u00e7o para o sucesso coletivo, para o bem comum. Todos sair\u00e3o ganhando e a largada para esse processo, mais uma vez, est\u00e1 no olhar mais humano e altru\u00edsta de quem lidera. Todo aquele que conduz uma equipe precisa estar a servi\u00e7o, se empenhar para que o seu time esteja psicologicamente seguro e assim seja capaz de atingir a alta performance.<\/p>\n\n\n\n<p>Nunca se esque\u00e7a: <strong>liderar com amor<\/strong> \u00e9 tamb\u00e9m estar focado na amplia\u00e7\u00e3o de consci\u00eancia para obter neg\u00f3cios e <strong>lideran\u00e7as sustent\u00e1veis<\/strong> e capazes de causar impacto. N\u00e3o \u00e9 ser chefe, mas facilitador. \u00c9 dar o exemplo, ter atitude. Comece praticando a autoconsci\u00eancia, a presen\u00e7a em tudo o que faz. Observe as suas pr\u00e1ticas, os seus m\u00e9todos, o modo como vem agindo com a sua equipe.<\/p>\n\n\n\n<p>Como voc\u00ea vem atuando, reflita se suas atitudes s\u00e3o de chefe ou de l\u00edder.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Chefe ou Li\u0301der.  Como voce\u0302 inspira equipes?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/4h_wrNMPwaQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Assim, para ajudar voc\u00ea a avan\u00e7ar rumo \u00e0 empatia e \u00e0 compaix\u00e3o, apresento a seguir dicas pr\u00e1ticas do que observar nesse sentido, do que fazer:&nbsp;<\/p>\n\n\n\n<p><strong>&#8211; <\/strong>Esteja pr\u00f3ximo da sua equipe, presente em tudo o que fizer. Chega de conversar com os seus colaboradores com o celular na m\u00e3o, olhando mensagens.<\/p>\n\n\n\n<p><strong>&#8211;<\/strong> Pratique a escuta ativa e amorosa, aquela na qual apenas ouvimos e acolhemos o outro com a nossa aten\u00e7\u00e3o, sem interromper para expressar as nossas opini\u00f5es ou falar de n\u00f3s mesmos, ainda que a inten\u00e7\u00e3o seja a de ajudar. Apenas ou\u00e7a, deixando que o outro fale livremente.<\/p>\n\n\n\n<p><strong>&#8211;<\/strong> Coloque-se no lugar do outro, dialogue, busque entender. Abaixo os julgamentos, n\u00e3o tire conclus\u00f5es precipitadas.<\/p>\n\n\n\n<p><strong>&#8211;<\/strong> Acolha a sua pr\u00f3pria humanidade primeiro, para depois aceitar a do outro. Errar, erramos todos, somente assim \u00e9 poss\u00edvel avan\u00e7ar.<\/p>\n\n\n\n<p><strong>&#8211;<\/strong> Tenha em mente que ter feito o seu melhor, por hoje, j\u00e1 foi o suficiente.<\/p>\n\n\n\n<p>Amanh\u00e3 \u00e9 outro dia, cheio de oportunidades. Estejamos atentos a elas. Escolha liderar com o cora\u00e7\u00e3o, escolha ser <strong>humano antes de ser l\u00edder<\/strong>. Que a nossa for\u00e7a seja o amor! O nosso mundo precisa de mais Empatia.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"COMO TER EMPATIA PARA FAZER A DIFEREN\u00c7A DE VERDADE?\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/9Dqmj5dPR7I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>As novas habilidades podem ser desenvolvidas e treinadas. No meu livro, L\u00edder Humano Gera Resultado, trago cases de sucesso. Voc\u00ea pode fazer o<a href=\"https:\/\/ligiacosta.com.br\/livro\/\"> donwload gratuito<\/a> do primeiro cap\u00edtulo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Saiba mais como podemos ajudar voc\u00ea:<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Livro [download] Gratuito do primeiro cap\u00edtulo<\/h2>\n\n\n\n<p>Voc\u00ea pode fazer o download do primeiro cap\u00edtulo meu livro:&nbsp;<a href=\"https:\/\/ligiacosta.com.br\/livro\/\">L\u00edder Humano Gera Resultados<\/a>. Ficarei muito grata em contribuir com o seu desenvolvimento. O livro est\u00e1 dispon\u00edvel em formato digital kindle pela Amazon e f\u00edsico em todas as livrarias online, basta digitar no Google que voc\u00ea ser\u00e1 direcionado a uma loja virtual. Aqui no meu site voc\u00ea tamb\u00e9m encontra.<\/p>\n\n\n\n<p>Desejo que este artigo tenha contribu\u00eddo para o primeiro passo e te incentivado a sair da zona de conforto. Deixe seu principal aprendizado e entre em a\u00e7\u00e3o no momento presente, inscreva-se em programas de autodesenvolvimento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cursos e Treinamentos<\/h2>\n\n\n\n<p>Veja tudo que podemos oferecer para voc\u00ea clicando em&nbsp;<a href=\"https:\/\/ligiacosta.com.br\/blog\/cursos\/\">CURSOS<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hugs &amp; Kisses<br>Ligia Costa<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Ligia Costa Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar.&nbsp; Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o e falta de significado. N\u00e3o ter\u00e1 futuro a empresa que n\u00e3o considerar esses pontos, que n\u00e3o pensar na sa\u00fade mental de seus funcion\u00e1rios e na import\u00e2ncia de todos trabalharem motivados, encontrando sentido naquilo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":3860,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115,140],"tags":[],"class_list":["post-3795","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lideranca-humanizada","category-mindfulness"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa<\/title>\n<meta name=\"description\" content=\"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-08T02:02:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T15:13:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2021\/10\/Empatia-e-compaixao-o-futuro-da-lideranca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"370\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a\",\"datePublished\":\"2021-10-08T02:02:04+00:00\",\"dateModified\":\"2023-04-27T15:13:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\"},\"wordCount\":914,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"articleSection\":[\"Lideran\u00e7a humanizada\",\"Mindfulness\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\",\"name\":\"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2021-10-08T02:02:04+00:00\",\"dateModified\":\"2023-04-27T15:13:03+00:00\",\"description\":\"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa","description":"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/","og_locale":"pt_BR","og_type":"article","og_title":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa","og_description":"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.","og_url":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/","og_site_name":"Blog Ligia Costa","article_published_time":"2021-10-08T02:02:04+00:00","article_modified_time":"2023-04-27T15:13:03+00:00","og_image":[{"width":370,"height":250,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2021\/10\/Empatia-e-compaixao-o-futuro-da-lideranca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/"},"author":{"name":"","@id":""},"headline":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a","datePublished":"2021-10-08T02:02:04+00:00","dateModified":"2023-04-27T15:13:03+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/"},"wordCount":914,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"articleSection":["Lideran\u00e7a humanizada","Mindfulness"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/","url":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/","name":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2021-10-08T02:02:04+00:00","dateModified":"2023-04-27T15:13:03+00:00","description":"Chegamos ao limite. Do jeito que est\u00e1, n\u00e3o d\u00e1 mais para ficar. Os ambientes corporativos n\u00e3o comportam mais tanta desconex\u00e3o.","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/futuro-da-lideranca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Empatia e compaix\u00e3o: o futuro da lideran\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3795"}],"version-history":[{"count":3,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3795\/revisions"}],"predecessor-version":[{"id":5708,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/3795\/revisions\/5708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/3860"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}