{"id":5893,"date":"2024-03-14T11:24:31","date_gmt":"2024-03-14T14:24:31","guid":{"rendered":"https:\/\/ligiacosta.com.br\/blog\/?p=5893"},"modified":"2024-03-14T13:21:29","modified_gmt":"2024-03-14T16:21:29","slug":"sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos","status":"publish","type":"post","link":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/","title":{"rendered":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental."},"content":{"rendered":"\n<p>Nesta modernidade contempor\u00e2nea e l\u00edquida, como dizia o soci\u00f3logo e fil\u00f3sofo polon\u00eas, Zygmunt Bauman, tudo passa t\u00e3o r\u00e1pido que nada se solidifica, acontece em Austin a busca incessante por informa\u00e7\u00f5es, conhecimentos e trends inovadoras que ditam insights e orienta\u00e7\u00f5es para o ano de 2024.&nbsp;<\/p>\n\n\n\n<p>J\u00e1 era de se esperar que mais um ano brasileiros bateram recorde de p\u00fablico no evento, sendo a maior delega\u00e7\u00e3o estrangeira presente. Brasileiros s\u00e3o reconhecidos como early adopters, s\u00e3o antenados a inova\u00e7\u00e3o, est\u00e3o hiperconectados e sofrem de ansiedade.<\/p>\n\n\n\n<p>Segundo a pesquisa Digital 202 Global Overview Report, o Brasil \u00e9 o segundo pa\u00eds do mundo que mais passa tempo conectado \u00e0 internet.<\/p>\n\n\n\n<p>O Brasileiro passa quatro vezes mais tempo nas redes sociais do que os japoneses. Segundo a fonte Kepios, Digital 2024 Global Overview Report, Basmo.<\/p>\n\n\n\n<p><img fetchpriority=\"high\" decoding=\"async\" width=\"509\" height=\"381\" src=\"https:\/\/lh7-us.googleusercontent.com\/tH69Nk2kfDIZY_sRgTKUVHuwvmOSFRdNhACwFdmVr8P3NlK_YOm6mAvwwLkAW_AoCWmWAyzjXA_cLL06zY_yyxSv4-yJl8v8eoG1aZcMD6yqHsFy7TQs9G_LIunpZfJvsGPe0VE6vTUIihFLKuDr2lM\"><\/p>\n\n\n\n<p>Inova\u00e7\u00e3o e conectividade est\u00e3o correlacionados? Ser\u00e1 a busca por informa\u00e7\u00e3o apenas pela informa\u00e7\u00e3o, o excesso nas redes sociais, promove inova\u00e7\u00e3o ou ansiedade?&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>S\u00edndrome da Fadiga Informativa<\/strong><\/h2>\n\n\n\n<p>Na mesma semana do SXSW 2024 em Austin, no Brasil aconteceu o Vittude Summit, o maior evento de Sa\u00fade Mental do pa\u00eds. Professor Marcos Medanha, nos apresenta que enquanto 4% da popula\u00e7\u00e3o mundial sofreu com algum transtorno de ansiedade em 2019 (OMS, 27\/09\/2023), a preval\u00eancia estimada de transtornos mentais da popula\u00e7\u00e3o brasileira ap\u00f3s pandemia \u00e9 de 11,7%.<\/p>\n\n\n\n<p><strong>A S\u00edndrome da fadiga informativa \u00e9 causada pelo excesso de telas e a hiperconectividade social \u00e9 tamb\u00e9m o que nos gera exaust\u00e3o, o que vem tornando o Brasil, o pa\u00eds mais ansioso da Am\u00e9rica Latina.\u00a0<\/strong><\/p>\n\n\n\n<p>Quanto a busca pelo conhecimento e inova\u00e7\u00e3o agrega ou gera FOMO (fear of missing out)? De que adianta DADOS se n\u00e3o sou capaz de DECODIFIC\u00c1-LOS?&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Excesso de Informa\u00e7\u00e3o gera distra\u00e7\u00e3o<\/strong><\/h2>\n\n\n\n<p>Estamos cada vez mais incapazes de sustentar o foco. Segundo Killingsworth, um estudo de Harvard, nossa mente divaga 50% do tempo. A mente que divaga \u00e9 uma mente infeliz, n\u00e3o \u00e9 capaz de focar, n\u00e3o \u00e9 capaz de persistir em seus objetivos, n\u00e3o \u00e9 capaz de observar seus recursos internos e tem baixa resili\u00eancia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Uma nova consci\u00eancia<\/strong><\/h2>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<cite><strong>FEED YOURSELF WITH THE CONTENT THAT MATTER TO YOU AND BE AWARE ON HOW YOU DIGEST THIS INFORMATION.<\/strong> (Alimente-se com o conte\u00fado que ressoa para voc\u00ea e observe como voc\u00ea o digere)<\/cite><\/blockquote>\n\n\n\n<p>Note que essa frase em ingl\u00eas usa FEED (alimente) e DIGEST (digere), ambas palavras relacionadas ao CORPO, o sistema digestivo do ser humano e nos intestinos, considerado nosso segundo c\u00e9rebro, onde  temos neur\u00f4nios pensantes da mesma maneira que no c\u00e9rebro e no cora\u00e7\u00e3o.\u00a0<\/p>\n\n\n\n<p>O quanto na \u00e2nsia da agilidade e rapidez voc\u00ea se permite absorver informa\u00e7\u00f5es, diger\u00ed-las, criar e contribuir com projetos de impacto no seu ecossistema.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>O quanto voc\u00ea se permite desbloquear o melhor de Si para impactar os outros?&nbsp;<\/strong><\/h2>\n\n\n\n<p>No dia 07 de Mar\u00e7o de 2024, foi o dia de Diego Perez realizar um Keynote no Austin Convention Center, Ballrom D.&nbsp; Desbloqueando o seu melhor &#8220;EU&#8221; para si e para os outros, tradu\u00e7\u00e3o literal da palestra: <strong>Unloking your best Self for yourself and others<\/strong><\/p>\n\n\n\n<p><strong>Deixo o v\u00eddeo da palestra completa. Palestra SXSW EDU 2024 &#8211; Unlocking your best Self for yourself and others<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Unlocking Your Best Self for Yourself &amp; Others | SXSW EDU 2024 Keynote\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/lG-VSTrQ46Q?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Diego fala de tr\u00eas pilares:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sermos Radicalmente honestos <\/strong>&#8211; Como ser e dizer a verdade para voc\u00ea para si mesmo? De que maneira voc\u00ea pode abrir-se para observar e reconhecer a hist\u00f3ria de suas emo\u00e7\u00f5es<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Autoaceita\u00e7\u00e3o <\/strong>&#8211; Como aceitar quem voc\u00ea \u00e9. Entender que dentro de voc\u00ea existem pensamentos que voc\u00ea se orgulha e outros que voc\u00ea n\u00e3o ama! Observa-se sem julgamento \u00e9 um processo para permitir a imperman\u00eancia! Voc\u00ea vive em um universo onde h\u00e1 mudan\u00e7as o tempo todo! Abrace a mudan\u00e7a, comece aceitando ser quem voc\u00ea \u00e9, e aos poucos fa\u00e7a ajustes<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Constru\u00e7\u00e3o de h\u00e1bitos positivos <\/strong>&#8211; mova o corpo, comece a andar e perceba que precisava de nutri\u00e7\u00e3o saud\u00e1vel matinal, min\u00fasculo<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Voc\u00ea est\u00e1 pronto para desapegar-se do externo e olhar para si?<\/h2>\n\n\n\n<p>Quando voc\u00ea come\u00e7a a se desapegar do externo, voc\u00ea passa a ter insights e decodificar realmente os dados em informa\u00e7\u00e3o e isso come\u00e7a no seu corpo. Nossa tarefa \u00e9 encontrar o que atende \u00e0s nossas necessidades!<\/p>\n\n\n\n<p>Existem diversas ferramentas que contribuem para sairmos deste piloto autom\u00e1tico, da compara\u00e7\u00e3o, da competi\u00e7\u00e3o e da busca inconsciente de dados apenas pelos dados, mas \u00e9 necess\u00e1rio abrir-se para um processo de consci\u00eancia e de cura.<\/p>\n\n\n\n<p>\u00c9 um processo desafiador, mas n\u00e3o opressor. <strong>\u00c9 necess\u00e1rio negociar intencionalmente para desacelerar, criar pequenos momentos de pausa<\/strong>, repeti-los para cria h\u00e1bitos e construir novos com padr\u00f5es mais saud\u00e1veis e sustent\u00e1veis<\/p>\n\n\n\n<p>Pare de desejar controlar tudo, aprenda a servir, mas antes descubra como dizer n\u00e3o, isso far\u00e1 com que o que voc\u00ea diz seja poderoso. Cuide de si e aprenda a se amar, essa \u00e9 nossa li\u00e7\u00e3o.<\/p>\n\n\n\n<p>No final de sua fala, Diego convida a plat\u00e9ia para escrever:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><\/p>\n<cite>&#8220;Eu vou me amar&#8221;<br>&#8220;Tratarei minha energia como um recurso precioso&#8221;<br>&#8220;Me Amar me ajudar\u00e1 a servir bem as pessoas&#8221;<\/cite><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">O quanto voc\u00ea efetivamente tem se amado para servir?<\/h2>\n\n\n\n<p>Deixe seu coment\u00e1rio e me conte se essa reflex\u00e3o fez sentido. Voc\u00ea est\u00e1 pronto para SER Humano antes de SER L\u00edder?<\/p>\n\n\n\n<p id=\"ember2501\">Hugs&amp;Kisses<\/p>\n\n\n\n<p id=\"ember2502\">Ligia Costa<\/p>\n\n\n\n<p id=\"ember2503\">Contatos para Palestras, Treinamentos e Certifica\u00e7\u00f5es: WhatsApp: +55 13 99150-0479 (Jacque Laffont)<\/p>\n\n\n\n<p id=\"ember2504\"><a href=\"http:\/\/www.ligiacosta.com.br\/\">www.ligiacosta.com.br<\/a><\/p>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.instagram.com\/ligiacosta_tgitoday\/\n<\/div><\/figure>\n\n\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/www.youtube.com\/ligiacosta\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta modernidade contempor\u00e2nea e l\u00edquida, como dizia o soci\u00f3logo e fil\u00f3sofo polon\u00eas, Zygmunt Bauman, tudo passa t\u00e3o r\u00e1pido que nada se solidifica, acontece em Austin a busca incessante por informa\u00e7\u00f5es, conhecimentos e trends inovadoras que ditam insights e orienta\u00e7\u00f5es para o ano de 2024.&nbsp; J\u00e1 era de se esperar que mais um ano brasileiros bateram [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":5895,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[115],"tags":[163,164,162,127,119],"class_list":["post-5893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-lideranca-humanizada","tag-ansiedade","tag-hiperconectividade","tag-inovacao","tag-inteligencia-emocional","tag-lideranca-humanizada"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa\" \/>\n<meta property=\"og:description\" content=\"Nesta modernidade contempor\u00e2nea e l\u00edquida, como dizia o soci\u00f3logo e fil\u00f3sofo polon\u00eas, Zygmunt Bauman, tudo passa t\u00e3o r\u00e1pido que nada se solidifica, acontece em Austin a busca incessante por informa\u00e7\u00f5es, conhecimentos e trends inovadoras que ditam insights e orienta\u00e7\u00f5es para o ano de 2024.&nbsp; J\u00e1 era de se esperar que mais um ano brasileiros bateram [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Ligia Costa\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-14T14:24:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-14T16:21:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2024\/03\/fotosLigiaCosta2021_MikaAmato-669-2-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental.\",\"datePublished\":\"2024-03-14T14:24:31+00:00\",\"dateModified\":\"2024-03-14T16:21:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\"},\"wordCount\":954,\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"keywords\":[\"ansiedade\",\"hiperconectividade\",\"inova\u00e7\u00e3o\",\"intelig\u00eancia emocional\",\"lideran\u00e7a humanizada\"],\"articleSection\":[\"Lideran\u00e7a humanizada\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\",\"name\":\"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa\",\"isPartOf\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\"},\"datePublished\":\"2024-03-14T14:24:31+00:00\",\"dateModified\":\"2024-03-14T16:21:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/ligiacosta.com.br\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#website\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"name\":\"Blog Ligia Costa\",\"description\":\"Blog Ligia Costa\",\"publisher\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#organization\",\"name\":\"Blog Ligia Costa\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"contentUrl\":\"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png\",\"width\":344,\"height\":45,\"caption\":\"Blog Ligia Costa\"},\"image\":{\"@id\":\"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/","og_locale":"pt_BR","og_type":"article","og_title":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa","og_description":"Nesta modernidade contempor\u00e2nea e l\u00edquida, como dizia o soci\u00f3logo e fil\u00f3sofo polon\u00eas, Zygmunt Bauman, tudo passa t\u00e3o r\u00e1pido que nada se solidifica, acontece em Austin a busca incessante por informa\u00e7\u00f5es, conhecimentos e trends inovadoras que ditam insights e orienta\u00e7\u00f5es para o ano de 2024.&nbsp; J\u00e1 era de se esperar que mais um ano brasileiros bateram [&hellip;]","og_url":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/","og_site_name":"Blog Ligia Costa","article_published_time":"2024-03-14T14:24:31+00:00","article_modified_time":"2024-03-14T16:21:29+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2024\/03\/fotosLigiaCosta2021_MikaAmato-669-2-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#article","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/"},"author":{"name":"","@id":""},"headline":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental.","datePublished":"2024-03-14T14:24:31+00:00","dateModified":"2024-03-14T16:21:29+00:00","mainEntityOfPage":{"@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/"},"wordCount":954,"publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"keywords":["ansiedade","hiperconectividade","inova\u00e7\u00e3o","intelig\u00eancia emocional","lideran\u00e7a humanizada"],"articleSection":["Lideran\u00e7a humanizada"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/","url":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/","name":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental. - Blog Ligia Costa","isPartOf":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#website"},"datePublished":"2024-03-14T14:24:31+00:00","dateModified":"2024-03-14T16:21:29+00:00","breadcrumb":{"@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ligiacosta.com.br\/blog\/sxsw-2024-brasileiros-um-pais-de-inovadores-hiperconectados-e-ansiosos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/ligiacosta.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Al\u00e9m do SXSW 2024: Inova\u00e7\u00e3o, Hiperconectividade e o Desafio da Sa\u00fade Mental."}]},{"@type":"WebSite","@id":"https:\/\/ligiacosta.com.br\/blog\/#website","url":"https:\/\/ligiacosta.com.br\/blog\/","name":"Blog Ligia Costa","description":"Blog Ligia Costa","publisher":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ligiacosta.com.br\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/ligiacosta.com.br\/blog\/#organization","name":"Blog Ligia Costa","url":"https:\/\/ligiacosta.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","contentUrl":"https:\/\/ligiacosta.com.br\/blog\/wp-content\/uploads\/2022\/12\/ligia-costa-blog-logo.png","width":344,"height":45,"caption":"Blog Ligia Costa"},"image":{"@id":"https:\/\/ligiacosta.com.br\/blog\/#\/schema\/logo\/image\/"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/5893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/comments?post=5893"}],"version-history":[{"count":7,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/5893\/revisions"}],"predecessor-version":[{"id":5935,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/posts\/5893\/revisions\/5935"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media\/5895"}],"wp:attachment":[{"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/media?parent=5893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/categories?post=5893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ligiacosta.com.br\/blog\/wp-json\/wp\/v2\/tags?post=5893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}